{"id":17465,"date":"2013-02-08T15:48:35","date_gmt":"2013-02-08T14:48:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=17465"},"modified":"2023-01-17T13:15:27","modified_gmt":"2023-01-17T12:15:27","slug":"6189-terremoto-riaprono-8-negozi-dopo-sisma-pollino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6189-terremoto-riaprono-8-negozi-dopo-sisma-pollino\/","title":{"rendered":"Terremoto: riaprono 8 negozi dopo sisma Pollino"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>MORMANNO (CS)<\/strong> &#8211; &nbsp;Monsignor Nunzio Galantino, vescovo della diocesi di Cassano allo Jonio, ha simbolicamente restituito a otto commercianti di<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Mormanno le chiavi di altrettanti esercizi commerciali, e uno studio tecnico, che a seguito del sisma del 26 ottobre scorso erano stati chiusi perche&#8217; dichiarati inagibili. Ma il cantiere aperto dalla Diocesi, proprietaria dell&#8217;immobile, ha consentito di portare a termine i lavori di messa in sicurezza e adeguamento statico, realizzati con i fondi dell&#8217;otto per mille messi a disposizione dalla Cei su richiesta dello stesso vescovo.<\/p>\n<p style=\"text-align: justify;\">In meno di tre mesi, dunque, il ritorno alla normalita&#8217;. Con le serrande di 8 negozi che sono tornate ad alzarsi lungo via Ludovico Romano, nel cuore del paese.<\/p>\n<p style=\"text-align: justify;\">Alla cerimonia di riconsegna delle chiavi hanno preso parte tra gli altri, insieme al presule, anche il sindaco di Mormanno, Guglielmo Armentano; il parroco di Santa Maria del Colle, monsignor Giuseppe Oliva; il presidente dell&#8217;Istituto diocesano per il sostentamento del clero, monsignor Francesco Di Chiara; il direttore dell&#8217;ufficio tecnico diocesano, Raffaele Bloise; il direttore della Caritas diocesana, Raffaele Vidiri. (AGI) Cs2\/Adv (Segue) &#8220;Speranza e solidarieta&#8217; &#8211; ha commentato il Pastore della Chiesa cassanese &#8211; sono parole che acquistano un senso quando ci si impegna. Il nostro lavoro ha significato dare corpo a speranza e solidarieta&#8217;, restituendo fiducia ad 8 commercianti ed alle loro famiglie e, tramite essi, per molti aspetti, all&#8217;intera comunita&#8217; locale&#8221;.<\/p>\n<p style=\"text-align: justify;\">Ha quindi aggiunto monsignor Galantino con riferimento alle proteste che da Mormanno si levano contro le istituzioni per la mancata adozione di concrete misure di intervento a seguito del terremoto che peraltro con le sue scosse continua a flagellare la zona del Pollino: &#8220;Molte volte i bisogni della gente vengono accerchiati da demagogia e burocrazia: noi siamo riusciti a superarli.<\/p>\n<p style=\"text-align: justify;\">La protesta che si leva indica che i cittadini sono stanchi di parole al vento che restano tali: anche per questo il nostro impegno prosegue&#8221;. Al termine della manifestazione, il vescovo ha presieduto la santa messa, celebrata nella chiesa di san Rocco.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MORMANNO (CS) &#8211; &nbsp;Monsignor Nunzio Galantino, vescovo della diocesi di Cassano allo Jonio, ha simbolicamente restituito a otto commercianti di<\/p>\n","protected":false},"author":22,"featured_media":17466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-17465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=17465"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/17466"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=17465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=17465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=17465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}