{"id":174669,"date":"2022-08-20T06:20:57","date_gmt":"2022-08-20T04:20:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incidente-stradale-sulla-statale-18-tirrena-inferiore-tre-feriti\/"},"modified":"2023-01-16T17:11:39","modified_gmt":"2023-01-16T16:11:39","slug":"470264-incidente-stradale-sulla-statale-18-tirrena-inferiore-tre-feriti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/470264-incidente-stradale-sulla-statale-18-tirrena-inferiore-tre-feriti\/","title":{"rendered":"Incidente stradale sulla statale 18 &#8220;Tirrena Inferiore&#8221;: tre feriti"},"content":{"rendered":"<p class=\"v1MsoNormal\">CATANZARO &#8211; A causa di un incidente stradale,<strong> il transito \u00e8 temporaneamente interdetto lungo la statale 18 &#8220;Tirrena Inferiore&#8221;,<\/strong> all&#8217;altezza del km 368,8 a Gizzeria in provincia di Catanzaro.\u00a0 Il sinistro, le cui cause sono ancora in corso di accertamento, <strong>ha visto coinvolti 2 veicoli e 3 persone sono rimaste ferite<\/strong>.\u00a0 Il traffico viene deviato con indicazioni sul posto.<\/p>\n<p class=\"v1xmsonormal\">Sul posto sono presenti i sanitari del 118, le squadre Anas e le Forze dell&#8217;Ordine per la gestione dell&#8217;evento e per consentire il ripristino della viabilit\u00e0 nel pi\u00f9 breve tempo possibile.<\/p>\n<p><em>+++Aggiornamento<\/em><\/p>\n<p><b>Ripristinata la circolazione lungo la strada statale 18 &#8220;Tirrena Inferiore&#8221; precedentemente interrotta per incidente.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il transito \u00e8 temporaneamente interdetto a Gizzeria. Sul posto i sanitari del 118, squadre Anas e forze dell&#8217;ordine<\/p>\n","protected":false},"author":58,"featured_media":174670,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-174669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/174669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=174669"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/174669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/174670"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=174669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=174669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=174669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}