{"id":175081,"date":"2022-08-27T07:49:16","date_gmt":"2022-08-27T05:49:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sextortion-allerta-della-polizia-postale-cresce-il-numero-dei-minori-vittime\/"},"modified":"2023-01-16T17:12:06","modified_gmt":"2023-01-16T16:12:06","slug":"471345-sextortion-allerta-della-polizia-postale-cresce-il-numero-dei-minori-vittime","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/471345-sextortion-allerta-della-polizia-postale-cresce-il-numero-dei-minori-vittime\/","title":{"rendered":"Sextortion: allerta della Polizia Postale, cresce il numero dei minori vittime"},"content":{"rendered":"<p>ROMA &#8211; Negli ultimi mesi sono aumentati i casi di sextortion in danno di adolescenti attraverso i social network. Si tratta di un fenomeno, di solito rivolto al mondo adulto, che oggi per\u00f2, <strong>colpisce vittime minorenni<\/strong>, tanto <strong>fragili<\/strong> quanto <strong>inesperte<\/strong>. Sempre pi\u00f9 spesso la <strong>curiosit\u00e0 sessuale<\/strong> dei <strong>ragazzi<\/strong> li trasporta in un incubo fatto di <strong>ricatti, richieste insistenti di denaro e minacce<\/strong> di distruggerne la reputazione diffondendo sui social, <strong>immagini sessuali<\/strong> ottenute tramite live chat. Tutto inizia chattando con profili social di ragazze e ragazzi gentili e avvenenti, apprezzamenti e like per le foto pubblicate. Si passa poi alle <strong>video chat<\/strong> e le richieste si fanno man mano pi\u00f9 spinte.<\/p>\n<p>Nei giorni seguenti, il martellamento online include la richiesta di somme di denaro anche esigue, con la minaccia che, in caso di mancato pagamento, il materiale sessuale verr\u00e0 diffuso tra tutti i contatti, gli amici e i parenti. <strong>Le vittime, intrappolate tra la vergogna e la paura<\/strong> che le immagini intime possano essere viste dai loro contatti, tendono a tenersi tutto per s\u00e8, a non confidarsi con nessuno, in particolare con i genitori.Per questo motivo il fenomeno \u00e8 sottostimato, perch\u00e9 la denuncia impone ai ragazzi un disvelamento ai genitori, che a volte appare pi\u00f9 doloroso delle minacce dell\u2019estorsione.<\/p>\n<h3>I consigli della polizia postale<\/h3>\n<p>&#8211; Mai cedere al ricatto pagando le somme richieste. Non smetteranno di chiedere denaro se si paga, ma anzi capiranno che hai disponibilit\u00e0 economica e si faranno pi\u00f9 insistenti;<\/p>\n<p>&#8211; Non bisogna vergognarsi per aver condiviso immagini intime con sconosciuti. A quella et\u00e0 si \u00e8 curiosi e inesperti e spesso le persone che fanno queste cose sono criminali organizzati che conoscono le fragilit\u00e0 dei ragazzi;<\/p>\n<p>&#8211; Non cancellare i messaggi scambiati con gli estorsori, non chiudere i profili social su cui ai viene contattati, ma fare gli screen shot delle conversazioni e delle minacce e del profilo dell\u2019estorsore;<\/p>\n<p>&#8211; Fare una segnalazione sul portale <a href=\"https:\/\/quicosenza.it\/news\/1025\" target=\"_blank\" rel=\"noopener\">www.commissariatodips.it<\/a> per chiedere aiuto, da soli \u00e8 pi\u00f9 difficile risolvere questo tipo di problemi;<\/p>\n<p>&#8211; Parlarne con i genitori o con un adulto di fiducia, che sapranno come essere di aiuto per gestire la situazione;<\/p>\n<p>&#8211; Chi ha pi\u00f9 di 14 anni pu\u00f2 sporgere una denuncia, anche in modo autonomo, in qualsiasi ufficio di Polizia.<\/p>\n<p>Consigli per i genitori:<\/p>\n<p>La sextortion \u00e8 un fenomeno che sta interessando un numero esponenziale di ragazzi\/e in rete. Si tratta di adulti e\/o organizzazioni criminali che avvicinano online gli adolescenti, li spingono in conversazioni virtuali di tipo sessuale, acquisiscono immagini e video intimi e poi richiedono somme di denaro per evitare la pubblicazione online del materiale privato. Se ai propri figli capita qualcosa di simile:<\/p>\n<p>&#8211; Non bisogna giudicare irresponsabile il loro comportamento, ma valutare che la vergogna e il senso di panico che possono provare li mettono a rischio di compiere atti impulsivi;<\/p>\n<p>&#8211; Ascoltare quanto i figli racconta, acquisire con calma tutte le informazioni e rassicurarli che non sono i soli ad essere incappati in questo tipo di situazioni;<\/p>\n<p>&#8211; Procurarsi gli screen shot delle conversazioni con gli estorsori e recarsi quanto prima in un ufficio di Polizia per sporgere una denuncia: la tempestivit\u00e0 in questi casi \u00e8 fondamentale per risolvere al meglio le indagini.<\/p>\n<p>&#8211; Non cancellare immagini, video e non chiudere i profili social prima di aver fornito queste informazioni alla Polizia;<\/p>\n<p>&#8211; Fare una segnalazione su <a href=\"https:\/\/quicosenza.it\/news\/1025\" target=\"_blank\" rel=\"noopener\">www.commissariatodips.it<\/a> e chiedere informazioni e supporto, se occorre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono minori per lo pi\u00f9 tra i 15 e i 17 anni e anche pi\u00f9 piccoli. Come comportarsi e cosa fare se ci si imbatte in un questo fenomeno con un enorme potenziale di pericolosit\u00e0<\/p>\n","protected":false},"author":42,"featured_media":175082,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-175081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/175081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=175081"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/175081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/175082"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=175081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=175081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=175081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}