{"id":175818,"date":"2022-09-10T14:04:40","date_gmt":"2022-09-10T12:04:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-primo-ko-al-marulla-cheddira-gela-il-marulla-e-regala-il-successo-al-bari\/"},"modified":"2023-01-16T17:12:56","modified_gmt":"2023-01-16T16:12:56","slug":"473436-cosenza-primo-ko-al-marulla-cheddira-gela-il-marulla-e-regala-il-successo-al-bari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/473436-cosenza-primo-ko-al-marulla-cheddira-gela-il-marulla-e-regala-il-successo-al-bari\/","title":{"rendered":"Cosenza, primo ko casalingo. Cheddira gela il Marulla e regala il successo al Bari"},"content":{"rendered":"<p>COSENZA &#8211; Il Cosenza rimedia la prima sconfitta casalinga della stagione, <strong>cadendo al Marulla per mano di un ottimo Bari<\/strong> che gioca una partita a viso aperto, sfruttando nel migliore dei modi, con un colpo di testa du Cheddira, una delle tante occasioni create, compreso un<strong> calcio di rigore calciato in curva da Antenucci<\/strong> in avvio di match. Il Cosenza deve invece fare mea culpa per a<strong>ver sprecato almeno 4 nitide occasioni da rete<\/strong> (tutte nel primo tempo) inclusa la traversa colpita da Brignola.\u00a0 Primo tempo emozionante con occasioni da una parte e dell&#8217;altra ma<strong> chiuso in vantaggio dal Bari in goal con la girata di testa di Cheddira <\/strong>all&#8217;ultimo secondo dei 4&#8242; di recupero concessi.\u00a0Si partire con il botto e con <strong>Antenucci calcia in curva un calcio di rigore dopo appena 6&#8242; minuti<\/strong>.<strong> Caprile si supera su Merola<\/strong> che poi si vede ribattuta sulla linea da Terranova la ribattuta in mezza rovesciata. <strong>Brignola si divora il vantaggio spedendo fuor<\/strong>i di sinistro con Florenzi tutto solo mentre al 37&#8242; <strong>la sua girata di sinistro dl limite si stampa sulla traversa<\/strong>. <strong>Matosevic respinge la botta di Terranova<\/strong> ma appare incerto sul colpo di testa dell&#8217;attaccante biancorosso. Fatta eccezione per una conclusione di Merola terminata fuori, nella ripresa il Cosenza non riesce praticamente mai a rendersi pericoloso con il Bari che chiude tutti gli spazi e si rende pericoloso con un destro al volo di Antenucci. Nel finale di gara il doppio giallo di Florenzi chiude un match amaro per i rossoblu, dolcissimo per i biancorossi che restano imbattuti.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/16005\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-473509\" src=\"https:\/\/quicosenza.it\/news\/16005\" alt=\"\" width=\"554\" height=\"369\" title=\"\"><\/a><\/p>\n<p>Bisoli lancia dal primo minuto Merola al posto di D&#8217;Urso mentre con Panico acciaccato sulla corsia di sinistra c&#8217;\u00e8 Martino. Partita subito bollente non solo per la temperatura praticamente estiva e il tifo delle due tifoserie, ma per quanto accaduto gi\u00e0 al 3&#8242; di gioco con <strong>un calcio di rigore assegnato al Bari per un tocco di mani in area di Rigione<\/strong>. L&#8217;arbitro in un primo momento fa proseguire l&#8217;azione ma poi, su richiamo del Var, concede il penalty dopo averlo rivisti. Dopo altre 3 minuti di attesa e proteste sul dischetto si presenta <strong>Antenucci che calcia fortissimo, ma spara alto sopra la traversa<\/strong>. Bari decisamente pi\u00f9 propositivo in avvio con le conclusioni di Botta (deviata) e dello stesso Antenucci (fuori). I rossoblu che ci mettono un p\u00f2 a carburare ma attorno al 20&#8242; prendono possesso del centrocampo <strong>e al 27&#8242; costruiscono una doppia colossale occasione da rete<\/strong><strong>\u00a0con Merola<\/strong>: la prima su cross di Florenzi con l&#8217;attaccate conclude\u00a0 sottomisura ma trova la strepitosa respinta di Caprile. Sulla respinta \u00e8 ancora l&#8217;attaccante a colpire in rovesciata, ma questa volta il pallone viene deviato sulla linea da Terranova.\u00a0<strong>Al 34&#8242; nuova grandissima occasione per il Cosenza<\/strong>. Brescianini lancia in profondit\u00e0<strong> Brignola che si invola verso l&#8217;area di rigore<\/strong>. L&#8217;ex attaccante del Benevento non vede Florenzi appostato tutto solo sul secondo palo e calcia con un <strong>improbabile esterno sinistro<\/strong> che si perde sul fondo per la disperazione del compagno di sqaudra e dei tifosi. Il Cosenza adesso \u00e8 padrone del campo e a<strong>l 37&#8242; \u00e8 la traversa a negare il vantaggio risputando in campo il bellissimo sinistro a giro di Brignola dal limite<\/strong>. Al 42&#8242; \u00e8 il Bari invece a rendersi pericolosissimo con una <strong>botta di Terranova dal limite che Matosevic vola a deviare in angolo<\/strong>. Il primo tempo sembra concludersi sul nulla di fatto quando,<strong> nell&#8217;ultimo dei 4&#8242; minuti di recupero<\/strong> <strong>concessi Cheddira porta in vantaggio il Bari<\/strong> girando di testa nell&#8217;angolino un cross dalla sinistra di Ricci, con Matosevic non proprio impeccabile.<\/p>\n<div id=\"attachment_473511\" style=\"width: 531px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/quicosenza.it\/news\/16006\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-473511\" class=\"wp-image-473511\" src=\"https:\/\/quicosenza.it\/news\/16006\" alt=\"\" width=\"521\" height=\"347\" title=\"\"><\/a><p id=\"caption-attachment-473511\" class=\"wp-caption-text\">Foto Francesco Donato<\/p><\/div>\n<p>La ripresa si apre senza cambi e con il Cosenza costretto a risalire la china dopo aver sprecato tanto nel primo tempo. Ci prova subito <strong>Merola al 48&#8242; con una girata in area<\/strong> sul primo palo che termina fuori. Decisamente pi\u00f9 pericoloso<strong> il destro al volo dal limite di Antenucci<\/strong> al minuti 53&#8242;, con il pallone che esce di un nulla alla sinistra di Matosevic. Il caldo non concede stregua con i calciatori costretti a dissetarsi spesso per combattere le alte temperature. Mentre Il Bari chiede un nuovo calcio di rigore per una caduta di Cheddira in area, Dionigi inserisce Gozzi e D&#8217;Urso per Rispoli e Brignola. Ma nonostante il possesso palla i rossoblu non riescono a sfondare mentre gli ospiti trovani ampi spazi per colpire in contropiede come al minuto 69&#8242; quando <strong>Matosevic respinge una conclusione di Ricci<\/strong> da posizione decentrata. I<strong>l tecnico del Cosenza prova il tutto per tutto<\/strong> inserendo a met\u00e0 ripresa anche Zilli e Butic ma la musica non cambia, anche perch\u00e8 i ritmi calano e il Bari chiude tutti i varchi. A poco meno di 5&#8242; dal termine Zilli frana in area ma si becca il cartellino giallo per simulazione. Pesante invece a 2&#8242; dal termine<strong> il doppio giallo rimediato da Florenzi che lascia i rossoblu in dieci<\/strong>. Dopo 7&#8242; minuti di recupero il triplice fischio che decreta la seconda sconfitta stagionale del Cosenza, la prima al Marulla.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La gallery del match a cura di Francesco Donato<\/strong><span style=\"color: #0000ff;\"><strong> (<a href=\"https:\/\/quicosenza.it\/news\/16007\" target=\"_blank\" rel=\"noopener\">QUI tutte le foto<\/a>)<\/strong><\/span><\/p>\n\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p><strong>COSENZA CALCIO (4-3-3):<\/strong> Matosevic; Rispoli (61&#8242; Gozzi), Rigione, Vaisanen, Martino; Florenzi, Voca (79&#8242; Cal\u00f2), Brescianini (71&#8242; Butic); Brignola, Larrivey (71&#8242; Zilli), Merola (61&#8242; D&#8217;Urso)<br \/>\n<strong>Panchina: <\/strong>Marson, Meroni, Caimigliano, Venturi, Gozzi, Cal\u00f2, Kornvig, Vallocchia, Prestianni, Butic, Zilli, D\u2019Urso, Sidibe<strong><br \/>\n<\/strong>\u00a0<strong>Allenatore:<\/strong>\u00a0Davide Dionigi<\/p>\n<p><strong>SSC BARI (4-3-1-2):<\/strong> Caprile; Pucino, Terranova, Di Cesare, Ricci; Mallamo (79&#8242; Benedetti), Maiello, Folorunsho; Botta (76&#8242; Salcedo); Antenucci (79&#8242; Cangiano), Cheddira (92&#8242; Vicari)<br \/>\n<strong>Panchina:<\/strong> Frattali, Polverino, D\u2019Errico, Gigliotti, Vicari, Galano, Bosisio, Bellomo, Cangiano, Dorval, Benedetti, Zuzek<br \/>\n<strong>Allenatore:<\/strong> Michele Mignani<\/p>\n<p><strong>Arbitro:\u00a0<\/strong>Signor Matteo Gariglio di Pinerolo<strong><br \/>\nAssistenti:\u00a0<\/strong>Signori Andrea Zingarelli di Siena e Thomas Miniutti di Maniago<br \/>\n<strong>IV Uomo:\u00a0<\/strong>Signor Andrea Ancora di Roma 1<br \/>\n<b>VAR:\u00a0<\/b>Signori Federico La Penna di Roma 1 e Valerio Vecchi di Lamezia Terme<\/p>\n<p><strong>Ammoniti:<\/strong> Florenzi (C), Di Cesare (B), Zilli (C), Cangiano (B)<br \/>\n<strong>Espulsi:<\/strong> Florenzi (C)<\/p>\n<p><strong>Angoli: <\/strong>3-3<br \/>\n<strong>Recupero: <\/strong>4&#8242; p.t. &#8211; 7&#8242; s.t.<\/p>\n<p><strong>NOTE:<\/strong> Pomeriggio soleggiato ed estivo a Cosenza con una temperatura di 33 gradi. Terreno del Marulla in buone condizioni. Presenti poco pi\u00f9 di 9mila spettatori compresi un migliaio tifosi del Bari sistemati nel settore ospiti<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primo tempo vibrante con occasioni da una parte e dell&#8217;altra compreso un rigore sbagliato dal Bari che passa con Cheddira<\/p>\n","protected":false},"author":23,"featured_media":175819,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19],"class_list":["post-175818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/175818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=175818"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/175818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/175819"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=175818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=175818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=175818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}