{"id":175923,"date":"2022-09-12T17:00:43","date_gmt":"2022-09-12T15:00:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/de-magistris-sanita-pubblica-ed-efficiente\/"},"modified":"2023-01-16T17:13:03","modified_gmt":"2023-01-16T16:13:03","slug":"473804-de-magistris-sanita-pubblica-ed-efficiente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/473804-de-magistris-sanita-pubblica-ed-efficiente\/","title":{"rendered":"De Magistris a Castrovillari: &#8220;Sanit\u00e0 pubblica ed efficiente&#8221;. E visita l&#8217;ospedale cittadino"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Prosegue la campagna elettorale di <strong>Luigi De Magistris<\/strong>\u00a0che, a <strong>Castrovillari, ha visitato all&#8217;ospedale &#8220;Ferrari&#8221;<\/strong> ed \u00e8 tornato a parlare soprattutto di <strong>sanit\u00e0, diritto alla salute e diritti sociali dei calabresi<\/strong>. Tra le principali criticit\u00e0 evidenziate riguardo l\u2019ospedale di Castrovillari, quella che riguarda l\u2019Unit\u00e0 Operativa di Riabilitazione Intensiva, che si attende da oltre 10 anni, mentre chi, fin da subito, potrebbe dirigerla e organizzarla \u00e8 confinato in altra sede, senza alcun ruolo operativo e dunque costretto, suo malgrado, a non far nulla dal 2018.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/16021\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-473808\" src=\"https:\/\/quicosenza.it\/news\/16021\" alt=\"\" width=\"545\" height=\"372\" title=\"\"><\/a><\/p>\n<p>&#8220;<strong>La sanit\u00e0 \u00e8 una delle piaghe del meridione e della Calabria<\/strong> &#8211; ha detto de Magistris nel suo intervento &#8211; e proprio da questo ospedale<strong> faccio un appello ai cittadini di scegliere bene da che parte stare<\/strong>. Ed al sistema consociativo che esiste in questa terra, che conosco bene, dico di arrendersi. N<strong>oi stiamo con gli oppressi e lo facciamo con umilt\u00e0<\/strong> ma con grande determinazione. Per cui, non sottovalutateci&#8221;.\u00a0 De Magistris ha parlato ora del lavoro svolto in Consiglio Regionale dal capogruppo Ferdinando Laghi e dal consigliere Antonio Lo Schiavo; metodologia che \u2013 come detto da De Magistris \u2013 connoter\u00e0 anche l\u2019azione dei parlamentari di <strong>Unione Popolare<\/strong> dopo il 25 settembre&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il leader di Unione Popolare ha fatto tappa nella citt\u00e0 del Pollino parlando di sanit\u00e0 e diritti dei cittadini &#8220;scegliere bene da che parte stare&#8221;<\/p>\n","protected":false},"author":65,"featured_media":175924,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19,135],"class_list":["post-175923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina","tag-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/175923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=175923"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/175923\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/175924"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=175923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=175923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=175923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}