{"id":17623,"date":"2013-02-12T14:11:34","date_gmt":"2013-02-12T13:11:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=17623"},"modified":"2023-01-17T13:15:36","modified_gmt":"2023-01-17T12:15:36","slug":"6274-argento-sibari-entri-nel-patrimonio-unesco","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6274-argento-sibari-entri-nel-patrimonio-unesco\/","title":{"rendered":"Argento: Sibari entri nel patrimonio Unesco"},"content":{"rendered":"<p><div style=\"text-align: justify;\"><strong>SIBARI (CS)<\/strong> &#8211; L&#8217;iniziativa lanciata da&nbsp;&nbsp;Angelo Argento,&nbsp;candidato Pd al Senato nella circoscrizione calabrese, e&#8217; stata presentata questa mattina a Roma nel<\/div>\n<p>  <!--more-->  <\/p>\n<div style=\"text-align: justify;\">corso di una conferenza stampa alla presenza della presidente del Pd, Rosy Bindi, del commissario regionale del Pd calabrese, Alfredo D&#8217;Attorre, dell&#8217;attore e regista Massimo Ghini e di Antonio Pascuzzo, frontman del gruppo dei Rosso Antico (premio Tenco). Alla campagna per Sibari ha aderito anche l&#8217;altro capolista, Marco Minniti e tutti candidati del Pd calabrese.&nbsp;<\/div>\n<div style=\"text-align: justify;\">&nbsp;&nbsp;&nbsp;I due artisti saranno protagonisti dello spettacolo-evento organizzato per sabato 16 febbraio alTeatro Italia di Cassano Jonio, a partire dalle 18, proprio per sensibilizzare sul tema della difesa del suolo, dello sfruttamento dei beni culturali calabresi a partire dal disastro che ha colpito gli scavi della provincia di Cosenza.&nbsp;<br \/>&nbsp;&nbsp;&nbsp;&#8220;L&#8217;obiettivo e&#8217; rompere l&#8217;isolamento calabrese &#8211; ha detto Rosy Bindi &#8211; che pesa in modo terribile su tutti gli ambiti dello sviluppo della Regione e ne frena le potenzialita&#8217;. La cultura e&#8217; una strada eccellente per scardinare questo isolamento. Sibari e&#8217; un simbolo che il partito democratico e il futuro governo di centrosinistra devono assumere come metafora per comprendere una volta per tutte che &#8216;quello che fa bene al Mezzogiorno, fa bene a tutta l&#8217;Italia&#8217;.<\/div>\n<div style=\"text-align: justify;\">Non c&#8217;e&#8217; dubbio infatti che i problemi che vive Sibari sono anche il frutto di una gestione fallimentare del territorio da parte degli attuali amministratori&#8221;. &#8220;Salvare Sibari e&#8217; la nostra priorita&#8217; &#8211; ha spiegato Argento &#8211; Abbiamo una enorme infrastruttura immateriale che va da Taranto al Metaponto passando da Sibari per finire a Taormina.<\/div>\n<div style=\"text-align: justify;\">La fruizione di questi beni che costituiscono la Magna Grecia d&#8217;Italia deve essere il nostro imperativo. Il riconoscimento di questa vasta area come bene Patrimonio dell&#8217;Umanit\u00e1 consentira&#8217; a Sibari e al territorio che la circonda di avere finalmente le attenzioni che merita e le tutele indispensabili per evitare il ripetersi di episodi di incuria e trascuratezza simili a quelli che ha prodotto l&#8217;allagamento del parco&#8221;.<\/div>\n<div style=\"text-align: justify;\">&#8220;La tutela dell&#8217;Unesco non sarebbe fine a se stessa &#8211; continua Argento- ma si legherebbe ai riconoscimenti di altre eccellenze, come quelle agroalimentari del territorio calabrese, dal peperoncino alla liquirizia, dal bergamotto al gaglioppo che e&#8217; il piu&#8217; antico vitigno della storia dell&#8217;umanita&#8217;&#8221;.&nbsp;<\/div>\n<p> &nbsp;&nbsp;&nbsp;&#8220;L&#8217; iniziativa di sabato e la richiesta all&#8217;Unesco sono un modo concreto per tenere alta l&#8217;attenzione su un sito archeologico importante come quello di Sibari che non possiamo permetterci di perdere &#8211; sostiene D&#8217;Attorre &#8211; Scontiamo anni di malgoverno da parte del presidente Scopelliti tanto e&#8217; vero che l&#8217;unica iniziativa concreta in queste settimane e&#8217; stato l&#8217;intervento del ministro Barca che conferma la linea del partito: per noi i beni culturali sono una occasione vera di investimento&#8221;.<\/p>\n<p style=\"text-align: justify;\">&#8220;Il recupero di Sibari &#8211; ha chiosato Ghini &#8211; deve rappresentare quel punto d&#8217;incontro doveroso tra un progetto culturale e la politica, specie dopo anni in cui la cultura non ha rappresentato una priorita&#8217; per i governi di centrodestra e, ahime&#8217;, in qualche caso e&#8217; stata trascurata anche dal centrosinistra. Ora abbiamo l&#8217;occasione per dimostrare che siamo in grado di riportare alla luce quell&#8217;inestimabile patrimonio sommerso di bellezze, ricchezze e cultura&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SIBARI (CS) &#8211; L&#8217;iniziativa lanciata da&nbsp;&nbsp;Angelo Argento,&nbsp;candidato Pd al Senato nella circoscrizione calabrese, e&#8217; stata presentata questa mattina a Roma nel<\/p>\n","protected":false},"author":22,"featured_media":17624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-17623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=17623"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/17624"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=17623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=17623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=17623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}