{"id":176348,"date":"2022-09-24T11:00:23","date_gmt":"2022-09-24T09:00:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/maltempo-i-detriti-in-mare-visibili-dallo-spazio-e-ripresi-da-sentinel-3\/"},"modified":"2023-01-16T17:13:31","modified_gmt":"2023-01-16T16:13:31","slug":"475252-maltempo-i-detriti-in-mare-visibili-dallo-spazio-e-ripresi-da-sentinel-3","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/475252-maltempo-i-detriti-in-mare-visibili-dallo-spazio-e-ripresi-da-sentinel-3\/","title":{"rendered":"Maltempo: i detriti in mare visibili dallo spazio e ripresi da Sentinel-3"},"content":{"rendered":"<p>MILANO &#8211; Una lunga striscia di<strong> sedimenti alluvionali che colora per chilometri il mare Adriatico, dalla costa romagnola a quella pugliese<\/strong>, \u00e8 stata ripresa dallo spazio grazie al satellite Sentinel-3 del programma di osservazione della Terra Copernicus, di Agenzia spaziale europea (Esa) e Commissione europea. L&#8217;immagine, catturata domenica 18 settembre, mostra l&#8217;effetto del vento e delle correnti marine che hanno trasportato i sedimenti per chilometri lungo tutta la costa adriatica italiana, dipingendo le acque nei toni del marrone chiaro e dell&#8217;azzurro.<\/p>\n<p>Lo stesso satellite <strong>Sentinel-3 aveva catturato le fasi iniziali<\/strong> del fenomeno nelle primissime ore dell&#8217;alluvione: l&#8217;immagine, elaborata e diffusa lo scorso 16 settembre dalla piattaforma Adam (Advanced geospatial Data Management), mostrava i primi pennacchi di sedimenti che dalla foce dei fiumi marchigiani si riversavano in mare lungo oltre 80 chilometri di costa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo stesso satellite aveva catturato le fasi iniziali del fenomeno nelle primissime ore dell&#8217;alluvione avvenuta qualche giorno fa<\/p>\n","protected":false},"author":58,"featured_media":176349,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-176348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/176348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=176348"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/176348\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/176349"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=176348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=176348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=176348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}