{"id":17653,"date":"2013-02-12T16:00:04","date_gmt":"2013-02-12T15:00:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=17653"},"modified":"2023-01-17T13:15:37","modified_gmt":"2023-01-17T12:15:37","slug":"6290-droga-e-omicidio-operazione-ghost-condanne-confermate","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6290-droga-e-omicidio-operazione-ghost-condanne-confermate\/","title":{"rendered":"Droga e omicidio. Operazione &#8216;Ghost&#8217;. Condanne confermate"},"content":{"rendered":"<p><p><span style=\"font-size: 12px; line-height: 1;\">VIBO VALENTIA &#8211; I 31 imputati del processo Ghost r<\/span><span style=\"font-size: 12px; line-height: 1;\">iconosciuti a vario titolo responsabili di associazione a delinquere finalizzata alla produzione, al traffico e alla detenzione di sostanze stupefacenti sono stati nuovamente condannati. <\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px; line-height: 1;\">A c<\/span><span style=\"font-size: 12px; line-height: 1;\">onfermare l&#8217;integrale sentenza di primo grado emessa dal gup distrettuale, Assunta Maiore, il 19 marzo del 2012 \u00e8 stato il sostituto procuratore generale di Catanzaro, Domenico Prestinenzi, dinanzi alla Corte d&#8217;Appello presieduta dal giudice Maria Vittoria Marchian\u00f2.&nbsp;<\/span><span style=\"font-size: 12px; line-height: 1;\">Al centro del processo i risultati investigativi scaturiti dall&#8217;operazione denominata &#8220;Ghost&#8221;, scattata il 25 gennaio 2011 dopo due anni di indagini da parte della Squadra mobile di Vibo, con il coordinamento della Direzione distrettuale antimafia di Catanzaro. La centrale di &#8220;taglio&#8221; e smistamento della droga era stata individuata all&#8217;interno di un capannone di localita&#8217; &#8220;Felicello&#8221; a Gerocarne, centro delle Pre Serre, in provincia di Vibo Valentia. A capo dell&#8217;associazione viene collocato Piero Sabatino, 31 anni, condannato in primo grado, al termine del processo con rito abbreviato, a 11 anni, 11 mesi e 20 giorni. Altro capo dell&#8217;associazione veniva indicato in Antonino Zupo, 31 anni, che aveva rimediato 8 anni di reclusione, ma che \u00e8 stato poi ucciso in un agguato il 22 settembre scorso.<\/span><span class=\"Apple-tab-span\" style=\"font-size: 12px; line-height: 1; white-space: pre;\"><\/span><span style=\"font-size: 12px; line-height: 1;\">&nbsp;L&#8217;organizzazione, secondo gli inquirenti, avrebbe spacciato nel Vibonese, a Firenze, Lamezia Terme (Cz) e Cremona, con un giro d&#8217;affari valutato in 5mila euro al giorno. In primo grado il gup aveva inflitto 102 anni complessivi di carcere. Prossima udienza il 14 marzo per gli interventi dei difensori.<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; I 31 imputati del processo Ghost riconosciuti a vario titolo responsabili di associazione a delinquere finalizzata alla produzione, al traffico e alla detenzione di sostanze stupefacenti sono stati nuovamente condannati.<\/p>\n","protected":false},"author":22,"featured_media":17654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-17653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=17653"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/17654"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=17653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=17653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=17653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}