{"id":176662,"date":"2022-09-26T10:06:24","date_gmt":"2022-09-26T08:06:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incidente-stradale-a-cassano-allo-ionio-il-bilancio-e-di-2-feriti\/"},"modified":"2023-01-16T17:13:52","modified_gmt":"2023-01-16T16:13:52","slug":"476250-incidente-stradale-a-cassano-allo-ionio-il-bilancio-e-di-2-feriti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/476250-incidente-stradale-a-cassano-allo-ionio-il-bilancio-e-di-2-feriti\/","title":{"rendered":"Incidente stradale a Cassano allo Ionio: il bilancio \u00e8 di 2 feriti"},"content":{"rendered":"<p class=\"v1x_MsoBodyText\"><span class=\"v1x_ContentPasted0\">CASSANO ALLO IONIO (CS) &#8211; Incidente stradale <\/span>avvenuto questa mattina in corrispondenza del km 15,750, <strong>&#8216;Di Cammarata e degli Stombi&#8221;, nel territorio comunale di Cassano allo Ionio,<\/strong> in provincia di Cosenza. Il sinistro ha coinvolto due autovetture e<strong> causato il ferimento di due persone. <\/strong>A causa dell&#8217;incidente il <strong>t<\/strong>raffico \u00e8 provvisoriamente bloccato in entrambe le direzioni lungo la strada statale 534.<\/p>\n<p class=\"v1x_MsoBodyText\"><span class=\"v1x_ContentPasted0\">Il personale di Anas, delle Forze dell&#8217;Ordine e dei Vigili del Fuoco sono sul posto per la gestione della viabilit\u00e0 e per il ripristino della normale circolazione nel pi\u00f9 breve tempo possibile.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A causa dell&#8217;incidente il traffico \u00e8 provvisoriamente bloccato in entrambe le direzioni lungo la strada statale 534<\/p>\n","protected":false},"author":61,"featured_media":176663,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[19],"class_list":["post-176662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/176662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=176662"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/176662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/176663"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=176662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=176662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=176662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}