{"id":17716,"date":"2013-02-13T13:25:53","date_gmt":"2013-02-13T12:25:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=17716"},"modified":"2023-01-17T13:15:41","modified_gmt":"2023-01-17T12:15:41","slug":"6325-morto-figlio-cantante-ricchi-e-poveri-non-saranno-a-sanremo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6325-morto-figlio-cantante-ricchi-e-poveri-non-saranno-a-sanremo\/","title":{"rendered":"Morto figlio cantante Ricchi e Poveri, non saranno a Sanremo"},"content":{"rendered":"<p><strong>GENOVA<\/strong> &#8211; Alessio Gatti, figlio di 23 anni di Franco Gatti, membro dei Ricchi e Poveri, \u00e8 stato trovato morto oggi nella sua abitazione di via<\/p>\n<p>  <!--more-->  <\/p>\n<p>Capolungo a Nervi, nel levante di Genova. Secondo i primi accertamenti, il decesso sarebbe da ricondurre ad un overdose di stupefacenti, presumibilmente di cocaina. A dare notizia dell&#8217;accaduto, anche Fabio Fazio ad inizio conferenza stampa di questa mattina: aveva appena ricevuto una telefonata, \u00e8 purtroppo morto il figlio di Franco de I Ricchi e Poveri, dunque questa sera il gruppo non sar\u00e0 ospite, come previsto, della seconda serata del festival. Indubbiamente, per qualche secondo ha regnato il silenzio in conferenza.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>AGGIORNAMENTI:<\/strong><\/p>\n<p>In un&#8217; intervista di poche ore fa, Franco Gatti ha tenuto a precisare che suo figlio non era assolutamente dedito alle droghe. Al contrario, sin da piccolo era stato educato a starne lontano. Un ragazzo eccentrico e capoccione &#8211; come lo ha definito il padre &#8211; come tanti altri. Il motivo della sua morte per\u00f2 non era la cocaina. Alessio Gatti infatti, era un trader finanziario, e proprio lo stress per questo mestiere lo avrebbe ridotto in fin di vita.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GENOVA &#8211; Alessio Gatti, figlio di 23 anni di Franco Gatti, membro dei Ricchi e Poveri, \u00e8 stato trovato morto oggi nella sua abitazione di via<\/p>\n","protected":false},"author":22,"featured_media":17717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-17716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=17716"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/17717"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=17716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=17716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=17716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}