{"id":177194,"date":"2022-10-05T09:42:16","date_gmt":"2022-10-05T07:42:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/operazione-della-gdf-sequestri-per-un-milione-in-carcere-imprenditore-calabrese\/"},"modified":"2023-01-16T17:14:30","modified_gmt":"2023-01-16T16:14:30","slug":"477679-operazione-della-gdf-sequestri-per-un-milione-in-carcere-imprenditore-calabrese","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/477679-operazione-della-gdf-sequestri-per-un-milione-in-carcere-imprenditore-calabrese\/","title":{"rendered":"Operazione della Gdf, sequestri per un milione: in carcere imprenditore calabrese"},"content":{"rendered":"<p>PERUGIA &#8211; Il Nucleo di polizia economico-finanziaria e il Servizio centrale di <strong>investigazione sulla criminalit\u00e0 organizzata della guardia di finanza<\/strong> hanno dato esecuzione ad un&#8217;ordinanza di applicazione di misure cautelari emessa dal gip di Perugia <strong>nei confronti di imprenditori, professionisti e societ\u00e0 operanti sull&#8217;intero territorio provinciale, ritenuti responsabili, a vario titolo<\/strong>, del trasferimento fraudolento di valori, emissione ed utilizzo di fatture per operazioni inesistenti, autoriciclaggio, ricettazione, indebita percezione di erogazioni pubbliche, <strong>falsit\u00e0 ideologica e favoreggiamento dell&#8217;immigrazione clandestina.<\/strong><\/p>\n<p><strong> Disposta la custodia in carcere per un imprenditore di origine calabrese<\/strong> e per un consulente del lavoro, i domiciliari per un altro imprenditore edile originario sempre della Calabria indagato per intestazione fittizia ed indebita percezione di erogazioni pubbliche e l&#8217;obbligo di presentazione alla polizia giudiziaria nei confronti di sette persone, a vario titolo, coinvolte. <strong>Con lo stesso provvedimento \u00e8 stato disposto, infine, il sequestro preventivo finalizzato alla confisca<\/strong> del capitale sociale e del compendio aziendale di sei imprese, di immobili auto e disponibilit\u00e0 finanziarie per un valore complessivo di oltre un milione di euro. Le complesse indagini, avviate nel 2020 e coordinate dalla Procura del capoluogo umbro, con l&#8217;impiego delle pi\u00f9 avanzate tecniche di investigazione, unitamente ad appostamenti, pedinamenti, <strong>esame di documentazione contabile, amministrativa e finanziaria hanno consentito di delineare quello che \u00e8 ritenuto un articolato<\/strong> quadro indiziario in relazione a plurimi casi di intestazioni fittizie di quote societarie ed immobili, di emissione ed utilizzo di fatture per operazioni inesistenti e di reimpiego dei connessi proventi illeciti, riconducibili a soggetti gi\u00e0 gravati da precedenti penali o di polizia per associazione mafiosa o destinatari di misure di prevenzione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Responsabili, a vario titolo, del trasferimento fraudolento di valori, autoriciclaggio, ricettazione, indebita percezione di erogazioni pubbliche, falsit\u00e0 ideologica e favoreggiamento dell&#8217;immigrazione clandestina<\/p>\n","protected":false},"author":61,"featured_media":177195,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-177194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/177194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=177194"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/177194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/177195"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=177194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=177194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=177194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}