{"id":177676,"date":"2022-10-13T10:21:24","date_gmt":"2022-10-13T08:21:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/con-gli-amici-animali-anche-dopo-la-morte-commissione-sanita-approva-proposta-di-legge\/"},"modified":"2023-01-16T17:15:01","modified_gmt":"2023-01-16T16:15:01","slug":"479230-con-gli-amici-animali-anche-dopo-la-morte-commissione-sanita-approva-proposta-di-legge","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/479230-con-gli-amici-animali-anche-dopo-la-morte-commissione-sanita-approva-proposta-di-legge\/","title":{"rendered":"Con gli amici animali anche dopo la morte: commissione sanit\u00e0 approva proposta di legge"},"content":{"rendered":"<p>CATANZARO &#8211; La Terza Commissione regionale Sanit\u00e0 <strong>ha approvato la proposta di legge di iniziativa del consigliere forzista Katya Gentile che disciplina la cremazione<\/strong>. Una proposta che integra la legge regionale n. 48 del 29 Novembre 2019, (Disposizioni in materia funeraria e polizia mortuaria) che comprendeva anche la cremazione. L&#8217;articolo 16 che disciplinava tale pratica funeraria, per\u00f2, <strong>\u00e8 stato successivamente abrogato per effetto di una impugnativa del governo<\/strong> e della conseguente legge regionale n. 14 del 2 luglio del 2020.<\/p>\n<p>Adesso l&#8217;ok dato dalla Terza Commissione alla proposta di legge <strong>del consigliere Katya Gentile, rappresenta un importante passo avanti<\/strong> per colmare un vuoto normativo su una materia delicata fino ad oggi non disciplinata dalla Regione Calabria. Con il testo di legge si disciplina, tra l&#8217;altro, <strong>l&#8217;autorizzazione alla cremazione e si regolamenta l&#8217;affidamento, la conservazione e la dispersione delle ceneri<\/strong>. La Terza Commissione ha inoltre approvato l&#8217;emendamento che introduce disposizioni relative <strong>alla tumulazione con gli animali d&#8217;affezione<\/strong>. Il testo prevede che in presenza di volont\u00e0 espressa dal defunto o dagli eredi sia possibile tumulare, <strong>previa cremazione, le ceneri degli animali di affezione<\/strong>, riposte in un&#8217;urna separata, nello stesso loculo del defunto o nella relativa tomba di famiglia.<\/p>\n<p>&#8220;Anche questa \u00e8 una norma di civilt\u00e0&#8221; \u2013commenta la Presidente della Sesta Commissione consiliare <strong>Katya Gentile.<\/strong> Per quanto riguarda, in particolare, la cremazione dei defunti, Gentile sottolinea che &#8220;in Calabria quella dei cimiteri \u00e8 una emergenza che si trascina da anni. <strong>C&#8217;\u00e8 carenza di spazi, i feretri rimangono accatastati per mesi in attesa della sepoltura.<\/strong> Le interminabili liste di attesa per la concessione di un loculo, sottopongono i familiari ad una ulteriore sofferenza, risultando lesivi della dignit\u00e0 umana. Anche per questi motivi \u00e8 in aumento la richiesta di cremazione. Rispetto al Nord Italia, per\u00f2, nel Meridione sono ancora pochi gli impianti, solo uno quello attivo in Calabria. <strong>E ci\u00f2 comporta una serie di disagi e criticit\u00e0.<\/strong> I familiari dei defunti che scelgono di essere cremati, sono costretti a trasferire il feretro in altre regioni e quindi a sostenere maggiori spese, con il rischio concreto di essere inseriti in liste d&#8217;attesa molto lunghe&#8221;. <strong>La proposta di legge adesso sar\u00e0 discussa in Consiglio regionale.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La proposta presentata dalla consigliera Gentile. &#8220;In presenza di volont\u00e0 espressa dal defunto potrebbe essere possibile tumulare le ceneri degli animali di affezione nello stesso loculo del defunto o nella relativa tomba di famiglia&#8221;<\/p>\n","protected":false},"author":61,"featured_media":177677,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-177676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/177676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=177676"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/177676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/177677"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=177676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=177676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=177676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}