{"id":178109,"date":"2022-10-22T17:00:49","date_gmt":"2022-10-22T15:00:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/a-diamante-liniziativa-clean-up-di-plastic-free\/"},"modified":"2023-01-27T12:17:14","modified_gmt":"2023-01-27T11:17:14","slug":"480609-a-diamante-liniziativa-clean-up-di-plastic-free","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/480609-a-diamante-liniziativa-clean-up-di-plastic-free\/","title":{"rendered":"A Diamante l&#8217;iniziativa &#8220;Clean up&#8221; di Plastic Free"},"content":{"rendered":"<p>DIAMANTE (CS) &#8211; Ogni anno, 12 milioni di tonnellate di plastica raggiungono i mari di tutto il mondo, l\u2019equivalente di un camion di rifiuti ogni minuto, e un milione e mezzo di animali, prevalentemente marini, muoiono a causa della plastica. L\u2019inquinamento da plastica \u00e8 ormai un problema che non possiamo pi\u00f9 ignorare. La Onlus <strong>Plastic Free<\/strong> \u00e8 nota per i suoi precedenti risultati e per aver gi\u00e0 rimosso dall\u2019ambiente <strong>oltre un milione di chilogrammi di plastica e rifiuti.<\/strong> Prossima iniziativa in una delle localit\u00e0 pi\u00f9 amate del tirreno cosentino, nel comune di Diamante, dove \u00e8 previsto un appuntamento di pulizia per il 30 ottobre.<\/p>\n<p>Il ritrovo sar\u00e0 sul Lungomare Viale Glauco di fronte Ufficio Postale alle ore 9.30. L&#8217;iniziativa durer\u00e0 circa 2 ore e l\u2019obiettivo sar\u00e0 pulire la spiaggia. Per qualsiasi dubbio \u00e8 possibile contattare il referente dell\u2019evento Alessandra Nucaro al numero <strong>3887711699<\/strong> oppure inviando un semplice <strong>WhatsApp. <\/strong>La partecipazione all\u2019evento \u00e8 completamente gratuita, baster\u00e0 <a href=\"https:\/\/quicosenza.it\/news\/16288\">cliccare QUI, <\/a>registrarsi come volontario,e\u00a0ricevere tutte le istruzioni necessarie.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-480611 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/10\/IMG_7646.jpeg\" alt=\"\" width=\"338\" height=\"422\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da oltre due anni, l\u2019associazione Plastic Free \u00e8 impegnata in questa tematica e forte della sua rete di referenti e canali social<\/p>\n","protected":false},"author":42,"featured_media":178110,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-178109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/178109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=178109"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/178109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/178110"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=178109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=178109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=178109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}