{"id":17826,"date":"2013-02-15T07:54:49","date_gmt":"2013-02-15T06:54:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=17826"},"modified":"2023-01-17T13:15:47","modified_gmt":"2023-01-17T12:15:47","slug":"6384-barca-perche-nessuno-interviene-a-sibari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6384-barca-perche-nessuno-interviene-a-sibari\/","title":{"rendered":"Barca, perch\u00e8 nessuno interviene a Sibari?"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>SIBARI (CS)<\/strong> &#8211; &nbsp;&#8220;Vedere un sito archeologico in queste condizioni e rendersi conto di quanto e&#8217; accaduto sugli argini del Crati, con probabili occupazioni<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">abusive del territorio, non fa certamente piacere&#8221;. Lo ha detto a Sibari, il ministro per la Coesione Sociale, Fabrizio Barca, che oggi e&#8217; in Calabria e ha visitato gli scavi archeologici, che recentemente sono stati allagati dall&#8217;esondazione del fiume Crati, e il museo annesso.<\/p>\n<p style=\"text-align: justify;\">&#8220;Non si puo&#8217; investire sul sito archeologico di Sibari se prima non c&#8217;e&#8217; un intervento sul territorio&#8221;, ha detto ancora Barca, che ha annunciato che vorra&#8217; verificare &#8220;perche&#8217; finora, pur avendo le risorse a disposizione, le autorita&#8217; non siano intervenute per il risanamento degli argini del fiume&#8221;. Barca ha anche ricordato che esiste un progetto sui Poli Museali di eccellenza del Mezzogiorno, che prevede interventi per 21 milioni di euro, da utilizzare anche per l&#8217;area di Sibari.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SIBARI (CS) &#8211; &nbsp;&#8220;Vedere un sito archeologico in queste condizioni e rendersi conto di quanto e&#8217; accaduto sugli argini del Crati, con probabili occupazioni<\/p>\n","protected":false},"author":22,"featured_media":17827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-17826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=17826"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/17827"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=17826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=17826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=17826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}