{"id":178549,"date":"2022-10-27T16:20:02","date_gmt":"2022-10-27T14:20:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/al-bar-per-comprare-la-droga-questura-chiude-il-locale-per-una-settimana\/"},"modified":"2023-01-16T17:16:00","modified_gmt":"2023-01-16T16:16:00","slug":"481835-al-bar-per-comprare-la-droga-questura-chiude-il-locale-per-una-settimana","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/481835-al-bar-per-comprare-la-droga-questura-chiude-il-locale-per-una-settimana\/","title":{"rendered":"Al bar per comprare la droga: Questura chiude il locale per una settimana"},"content":{"rendered":"<p>CROTONE &#8211; Il questore di Crotone, Marco Giambra, ha disposto la chiusura per sette giorni, per motivi di ordine pubblico, di due bar ubicati in citt\u00e0. La decisione \u00e8 stata presa dopo che i carabinieri hanno segnalato che i due locali erano frequentati da pregiudicati. <strong>In uno dei due bar, inoltre, si svolgeva, sempre secondo quanto accertato dai militari, un&#8217;attivit\u00e0 di spaccio di sostanze stupefacenti<\/strong> e venivano commessi altri reati. In particolare, nello stesso locale, il 15 ottobre scorso, un uomo, dopo avere giocato ai videopoker, aveva danneggiato i congegni elettronici con alcuni colpi di pistola, in presenza di altri avventori, e si era allontanato. La stessa persona era stata poi rintracciata ed arrestata dai carabinieri anche per il porto illegale della pistola con cui aveva sparato i colpi all&#8217;interno del locale. L&#8217;arma era stata recuperata e sequestrata dai militari<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; lo stesso posto in cui qualche giorno fa un uomo ha sparato contro alcuni videopoker. Identico provvedimento per un secondo bar. Entrambi frequentati da pregiudicati<\/p>\n","protected":false},"author":69,"featured_media":178550,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-178549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/178549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=178549"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/178549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/178550"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=178549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=178549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=178549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}