{"id":178769,"date":"2022-11-06T10:00:00","date_gmt":"2022-11-06T09:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/pnrr-al-comune-di-cassano-ionio-6-milioni-di-euro-per-scuole-e-asili\/"},"modified":"2023-01-16T17:16:14","modified_gmt":"2023-01-16T16:16:14","slug":"482458-pnrr-al-comune-di-cassano-ionio-6-milioni-di-euro-per-scuole-e-asili","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/482458-pnrr-al-comune-di-cassano-ionio-6-milioni-di-euro-per-scuole-e-asili\/","title":{"rendered":"Pnrr: al Comune di Cassano Ionio 6 milioni di euro per scuole e asili"},"content":{"rendered":"<p>CASSANO ALLO IONIO (CS) &#8211; Dal Pnrr altri 6 milioni di euro da destinare alla costruzione di scuole e asili a Cassano allo Ionio. Ad annunciarlo \u00e8 l&#8217;Amministrazione comunale con un comunicato in cui si afferma che &#8220;i Ministeri interessati dalla misura hanno promosso due progetti presentati dagli uffici comunali per costruire altrettante nuove infrastrutture a <strong>Sibari e Cassano centro&#8221;<\/strong>.<\/p>\n<p>&#8220;Nello specifico, con decreto del direttore generale e coordinatore dell&#8217;unit\u00e0 di missione per il Pnrr, il numero 74 datato 26 ottobre 2022) &#8211; si aggiunge nella nota &#8211; i <strong>due interventi candidati dal Comune di Cassano allo Ionio<\/strong> sono stati ammessi a finanziamento per un importo totale di poco pi\u00f9 di <strong>sei milioni di euro.<\/strong><\/p>\n<p>Andando <strong>nel dettaglio<\/strong> degli elaborati presentati dal Comune jonico questi riguardano la Missione 4 del Piano nazionale di ripresa e resilienza PNRR denominata &#8216;Istruzione e Ricerca&#8217; &#8211; Componente 1 &#8211; Potenziamento dell&#8217;offerta dei servizi di istruzione: dagli asili nido alle Universit\u00e0 &#8211; Investimento 1.1: &#8216;Piano per asili nido e scuole dell&#8217;infanzia e servizi di educazione e cura per la prima infanzia&#8217;, finanziato dall&#8217;Unione europea &#8211; Next Generation EU. Si tratta della demolizione e ricostruzione di una scuola per l&#8217;infanzia e realizzazione di asilo nido nel comune di Cassano in via Giovanni Amendola (per un importo pari a &amp;euro 2.869.576,71) e per la realizzazione di un asilo nido a Sibari (per un importo pari a &amp;euro 3.151.350,00.)&#8221;.<\/p>\n<p>\u00ab\u00c8 un risultato straordinario &#8211; ha commentato il sindaco, Gianni Papasso. &#8211; Non \u00e8 il primo progetto di edilizia scolastica &#8211; ha aggiunto Papasso &#8211; che ci viene finanziato e sono sicuro che non sar\u00e0 l&#8217;ultimo. Come Amministrazione comunale puntiamo da sempre ad offrire ai nostri ragazzi strutture scolastiche moderne, sicure ed al passo con i tempi dove si possa formare la classe dirigente della Cassano del domani\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco Papasso lo ha definito un risultato straordinario: &#8220;non \u00e8 il primo progetto di edilizia scolastica che ci viene finanziato e sono sicuro che non sar\u00e0 l&#8217;ultimo&#8221;<\/p>\n","protected":false},"author":42,"featured_media":178770,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[19],"class_list":["post-178769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/178769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=178769"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/178769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/178770"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=178769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=178769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=178769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}