{"id":178819,"date":"2022-11-02T16:55:02","date_gmt":"2022-11-02T15:55:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/commemorazione-dei-defunti-cerimonia-al-cimitero-di-colle-mussano\/"},"modified":"2023-02-01T18:38:39","modified_gmt":"2023-02-01T17:38:39","slug":"482583-commemorazione-dei-defunti-cerimonia-al-cimitero-di-colle-mussano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/482583-commemorazione-dei-defunti-cerimonia-al-cimitero-di-colle-mussano\/","title":{"rendered":"Commemorazione dei defunti: cerimonia al cimitero di Colle Mussano"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Il Sindaco Franz Caruso ha partecipato nel pomeriggio di oggi alla tradizionale cerimonia tenutasi al cimitero di Colle Mussano nel corso della quale il primo cittadino ha preso parte al solenne rituale della deposizione, <\/strong>a cura del I Reggimento Bersaglieri di Cosenza, di una corona di fiori davanti alla stele che ricorda i caduti di tutti le guerre, nelle immediate adiacenze della chiesa di Ges\u00f9 Risorto, all&#8217;interno del complesso cimiteriale.<\/p>\n<p>Insieme al Sindaco Franz Caruso, erano presenti alla cerimonia l&#8217;Amministratore apostolico della Diocesi di Cosenza-Bisignano, <strong>Monsignor Giuseppe Piemontese<\/strong> che ha impartito la benedizione a tutti i defunti, il Vicario del Prefetto di Cosenza, dottoressa Regina Antonella Bardari, il vicario del Questore, dott.Giuseppe Lanaia, il Colonnello Agatino Spoto, Comandante provinciale dell&#8217;Arma dei Carabinieri, il Comandante provinciale della Guardia di Finanza, Colonello Giuseppe Dell&#8217;Anna, il Comandante del I Reggimento Bersaglieri, Colonnello Francesco Ferrara, Il Comandante provinciale dei Vigili del Fuoco, Giampiero Rizzo,\u00a0 il Comandante del Distaccamento Aeronautico di Montescuro, Tenente colonnello Massimo Alligri e le altre autorit\u00e0 civili, miltari e religiose. Per l&#8217;Amministrazione comunale erano presenti, inoltre l&#8217;Assessore ai lavori pubblici di Palazzo dei Bruzi, Damiano Covelli, e il delegato del Sindaco ai Rapporti con le comunit\u00e0 religiose, Francesco Turco.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Sindaco Franz Caruso ha tenuto moltissimo, in occasione della commemorazione dei defunti ed in considerazione dell&#8217;afflusso di molti cittadini e visitatori che in questi giorni si recano a Colle Mussano per rendere omaggio ai propri cari, di offrire alla citt\u00e0 un&#8217;immagine del complesso cimiteriale quanto pi\u00f9 decorosa e dignitosa possibile. <strong>Per questo la struttura \u00e8 stata interessata in questi giorni da lavori di bonifica e pulizia generale<\/strong> cui \u00e8 seguita la piantumazione di fiori, la sistemazione delle aiuole e la collocazione di piante di Ibiscus sulla scalinata dalla quale si accede all&#8217;ingresso del vecchio cimitero. Queste operazioni, finalizzate ad un sensibile miglioramento del decoro della struttura, sono state coordinate dal dirigente del settore Infrastrutture e cimiteri, Arch.Giuseppe Bruno, con la fattiva collaborazione della funzionaria responsabile dei cimiteri cittadini, Simona Zicarelli.<\/p>\n<p>Sia al termine della cerimonia di questo pomeriggio che nel corso della mattinata, in prossimit\u00e0 della statua della Vergine, all&#8217;interno del complesso di Colle Mussano, i visitatori sono stati accolti da un sobrio accompagnamento musicale a cura del maestro Francesco Caligiuri, sassofonista cosentino, che dopo essersi diplomato al Conservatorio \u201cStanislao Giacomantonio\u201d ed aver collaborato con il Dipartimento jazz dello stesso conservatorio di Cosenza, \u00e8 attualmente docente di Musica d&#8217;insieme jazz al Conservatorio \u201cNiccol\u00f2 Paganini\u201d di Genova. Due i brani che il maestro Caligiuri ha eseguito, durante i suoi interventi nel corso della giornata dedicata ai defunti al cimitero di Colle Mussano: \u201cIl Silenzio\u201d e il \u201cTema d&#8217;amore\u201d dal film \u201cNuovo cinema Paradiso\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I militari del primo Reggimento Bersaglieri di Cosenza hanno deposto una corona di fiori davanti alla stele che ricorda i caduti di tutti le guerre<\/p>\n","protected":false},"author":69,"featured_media":178820,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19,135],"class_list":["post-178819","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-area-urbana","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/178819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=178819"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/178819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/178820"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=178819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=178819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=178819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}