{"id":179083,"date":"2022-11-07T15:56:15","date_gmt":"2022-11-07T14:56:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-poco-verde-pubblico-e-tanto-inquinamento-funaro-stiamo-invertendo-la-rotta\/"},"modified":"2023-01-16T17:16:36","modified_gmt":"2023-01-16T16:16:36","slug":"483236-cosenza-poco-verde-pubblico-e-tanto-inquinamento-funaro-stiamo-invertendo-la-rotta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/483236-cosenza-poco-verde-pubblico-e-tanto-inquinamento-funaro-stiamo-invertendo-la-rotta\/","title":{"rendered":"Cosenza, poco verde pubblico e tanto inquinamento. Funaro: &#8220;Stiamo invertendo la rotta&#8221;"},"content":{"rendered":"<div>COSENZA\u00a0 La<strong> vicesindaco ed assessore all&#8217;ambiente, Maria Pia Funaro,<\/strong> sottolinea la spinta propulsiva data dal sindaco Franz Caruso per rendere pi\u00f9 sicura, sostenibile e inclusiva la citt\u00e0 dei Bruzi, a margine della presentazione del Rapporto sull&#8217;ecosistema urbano, relativo al 2021, da cui sono emerse diverse criticit\u00e0. Per Cosenza, in particolare, si evidenzia <strong>una basso indice di verde pubblico a cui fa da contraltare un consistente tasso di inquinamento dell&#8217;aria<\/strong> dovuto alla congestione del traffico urbano in alcune zone. Si registra, poi, una scarsa incidenza di buone pratiche per l&#8217;adattamento ai cambiamenti climatici, mentre risulta pessima la gestione della raccolta dei rifiuti. Criticit\u00e0 \u00a0su cui ha inciso in maniera forte e determinata <strong>la nuova amministrazione, invertendo, finalmente, la rotta.<\/strong> Ed, infatti, un sostanziale miglioramento nell&#8217;inquinamento dell&#8217;aria si \u00e8 gi\u00e0 registrato grazie alle modifiche sulla viabilit\u00e0, in particolare, di via Roma e Piazza Bilotti, che sar\u00e0 certamente pi\u00f9 incisivo e definitivo quando sar\u00e0 operativo il Piano Urbano della Mobilit\u00e0 Sostenibile, la cui redazione \u00e8 stata affidata all&#8217;Unical. Importante svolta sulle buone pratiche per l&#8217;adattamento ai cambiamenti climatici, inoltre, \u00e8 dato dal<strong> progetto per &#8220;Interventi green blue&#8221;<\/strong> finanziato per circa 300 mila euro e \u00a0che sar\u00e0 realizzato\u00a0 nei pressi dell&#8217;ultimo lotto di via Popilia.<\/div>\n<h4>&#8220;Cosenza ecologica uno dei punti del programma del sindaco&#8221;<\/h4>\n<div>&#8220;Uno dei punti centrali e qualificanti del programma Cosenza2050 \u00e8 la visione di &#8220;Cosenza Ecologica&#8221;- ha affermato la vicesindaco ed assessore all&#8217;ambiente Maria Pia Funaro \u2013 . Con l&#8217;obiettivo, quindi, \u00a0di realizzare un percorso green, abbiamo previsto la realizzazione di due boschi urbani. Abbiamo, infatti, aderito sin dal nostro insediamento al progetto &#8220;Un albero per il futuro&#8221; promosso dal Ministero per la transizione Ecologica ed abbiamo sottoscritto un protocollo d&#8217;intesa con A0CO2. \u00a0Alla fine di questo primo anno di amministrazione si stima di riuscire a mettere a dimora circa<strong> 700 nuove specie arboree<\/strong>. A ci\u00f2 si aggiunge <strong>l&#8217;istituzione del Garante del Verde<\/strong> che ci porta ad essere la prima citt\u00e0 a sud di Napoli ad averlo costituito. Punto critico e <strong>nota dolente rimane, invece, la gestione dei rifiuti,<\/strong> su cui per\u00f2 siamo gi\u00e0 intervenuti approvando il nuovo piano dei rifiuti che sar\u00e0 messo in atto appena saranno concluse le procedure del relativo bando&#8221;.<\/div>\n<div><\/div>\n<div>&#8220;Su input del sindaco Franz Caruso \u2013 ha concluso Maria Pia Funaro \u2013 abbiamo bandito interventi spot e instabili per come hanno fatto <strong>i nostri predecessori che continuano ad autoincensarsi,<\/strong> dimentichi dei fallimenti di cui sono lastricati i propri percorsi. Noi\u00a0 preferiamo portare avanti, invece, un&#8217;azione corretta, improntata alla legalit\u00e0 ed alla trasparenza, armoniosa e strutturata, facendo rete anche con i Comuni pi\u00f9 virtuosi d&#8217;Italia, i cui risultati positivi saranno presto tangibili e non avranno bisogno di essere decantati da noi stessi. Sicuri di ci\u00f2, il giudizio lo lasciamo ai nostri concittadini, che sanno distinguere il grano dal loglio&#8221;.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il vicesindaco rassicura dopo le diverse criticit\u00e0 emerse a margine della presentazione del Rapporto sull&#8217;ecosistema urbano, relativo al 2021<\/p>\n","protected":false},"author":58,"featured_media":179084,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-179083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/179083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=179083"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/179083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/179084"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=179083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=179083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=179083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}