{"id":17990,"date":"2013-02-18T22:00:00","date_gmt":"2013-02-18T21:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=17990"},"modified":"2023-01-17T13:15:58","modified_gmt":"2023-01-17T12:15:58","slug":"6472-estorsione-a-mano-armata-per-un-banco-di-carciofi-due-arresti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6472-estorsione-a-mano-armata-per-un-banco-di-carciofi-due-arresti\/","title":{"rendered":"Estorsione a mano armata per un banco di carciofi: due arresti"},"content":{"rendered":"<p><strong>COSENZA<\/strong> &#8211;&nbsp;Al termine di una laboriosa attivit\u00e0 investigativa, ieri il personale della Polizia di Stato del Commissariato di Rossano ha dato esecuzione a due ordinanze di custodia cautelare degli arresti domiciliari &nbsp;nei confronti del pluripregiudicato Manzi Mario, classe 1967 e di suo figlio Manzi Alessandro, classe 1991, per i reati di estorsione continuata ed aggravata in concorso, detenzione abusiva di armi ed oggetti atti ad offendere.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Durante il regolare pattugliamento il personale del Commissariato in servizio di vigilanza notavano un commerciante rossanese che, visibilmente adirato, gridava in viale dei Normanni di Rossano. Gli operatori di polizia si fermavano apprendendo che poco prima aveva subito un&#8217;aggressione da parte del Manzi Mario, il quale aveva cercato di estorcergli del danaro con la minaccia che se non pagava non poteva stare pi\u00f9 in quella via a vendere carciofi con &nbsp;il suo mezzo altrimenti ci avrebbe messo suo figlio con il camion, e lo avrebbe ammazzato. Non ricevendo riscontro a tale richiesta estorsiva, il Manzi Mario prelevava dalla sua autovettura una mazza da baseball con la quale aggrediva la vittima, che, al fine di non essere percosso, riusciva a impossessarsi della mazza e, dopo una colluttazione, il Manzi Mario cadeva a terra e vistosi disarmato si allontanava a bordo della sua autovettura. A tali fatti delittuosi assistevano inermi i congiunti del malcapitato. Successivamente, mentre il personale di polizia era intento ad acquisire formale denuncia da parte dell&#8217;aggredito, Manzi e suo figlio ritornavano sul posto in cui era situato il mezzo dell\u2019ambulante trovandovi il padre ed il fratello del denunciante, i quali erano rimasti sul posto per sostituirlo. In tale occasione, Manzi Mario, armato di coltello, chiedeva dove fosse il figlio perch\u00e9 lo dovevano ammazzare, mentre il ragazzo, armato di un \u201cpugno di ferro\u201d con puntali acuminati e di un bastone chiodato, aggrediva l\u2019altro figlio della vittima, colpendolo al braccio nonch\u00e9 ad altre parti del corpo provocandogli dei tagli al giubbotto. I due congiunti, vista la situazione, strattonavano il giovane Manzi e dandosi a precipitosa fuga in direzione di un locale pubblico rimanevano in attesa dell\u2019arrivo di personale della polizia, allertato da altri testimoni. Avendo intuito l\u2019arrivo della Volante del Commissariato Manzi Mario e suo figlio Alessandro, si dileguavano frettolosamente per viale S. Angelo. Successivamente si accertava che il ragazzo con il bastone chiodato ed il pugno di ferro con lame acuminate, aveva colpito ripetutamente &nbsp;uno dei congiunti della vittima essendo evidenti i tagli al giubbotto che indossava. Alla luce del quadro indiziario raccolto dal personale del Commissariato, grave preciso e concordante, il Sostituto Procuratore della Repubblica di Rossano Quaranta richiedeva al GIP presso il Tribunale di Rossano, l\u2019emissione di un adeguata misura cautelare nei confronti di Manzi Mario e di suo figlio atteso il concreto pericolo di specifiche azioni recidive, considerando anche le modalit\u00e0 specifiche del grave fatto commesso, che evidenziano come gli indagati siano abituati a condotte violente nei confronti di terzi per ottenere ingiusti profitti. Il GIP dott. G. Labonia, applicava al Manzi Mario e al figlio la misura cautelare degli arresti domiciliari con divieto di comunicare con persone diverse da quelle che con loro coabitano, che veniva eseguita nella mattinata odierna.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211;&nbsp;Al termine di una laboriosa attivit\u00e0 investigativa, ieri il personale della Polizia di Stato del Commissariato di Rossano ha dato esecuzione a due ordinanze di custodia cautelare degli arresti domiciliari &nbsp;nei confronti del pluripregiudicato Manzi Mario, classe 1967 e di suo figlio Manzi Alessandro, classe 1991, per i reati di estorsione continuata ed aggravata [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":17991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-17990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=17990"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/17990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/17991"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=17990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=17990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=17990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}