{"id":179994,"date":"2022-11-24T08:35:29","date_gmt":"2022-11-24T07:35:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/caso-valentini-majorana-chiuse-le-indagini-sul-docente-di-matematica\/"},"modified":"2023-01-16T17:17:37","modified_gmt":"2023-01-16T16:17:37","slug":"485926-caso-valentini-majorana-chiuse-le-indagini-sul-docente-di-matematica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/485926-caso-valentini-majorana-chiuse-le-indagini-sul-docente-di-matematica\/","title":{"rendered":"Caso Valentini Majorana, chiuse le indagini sul docente di matematica"},"content":{"rendered":"<p>COSENZA &#8211; Chiuse le indagini da parte della Procura di Cosenza, sul caso delle presunte violenze sessuali da parte di un docente ai danni di alcune studentesse del liceo Valentini Majorana di Castrolibero. Le ipotesi di reato a carico del professore di matematica sono violenza sessuale, tentata violenza sessuale, molestie sessuali e tentata estorsione.<\/p>\n<p>L\u2019inchiesta risale al febbraio scorso per fatti che si sarebbero verificati dal 2016 al 2018, a seguito delle denunce di <strong>quattro studentesse,<\/strong> minorenni all&#8217;epoca dei fatti, e le indagini erano state avviate dai carabinieri di Rende e del Reparto operativo del Comando provinciale di Cosenza.<\/p>\n<p>Indagata anche l&#8217;ex dirigente scolastica per omissione d\u2019atti d\u2019ufficio. In qualit\u00e0 di pubblico ufficiale e pur essendone a conoscenza, avrebbe omesso di denunciare i fatti alle autorit\u00e0 preposte. La vicenda sal\u00ec alla ribalta nazionale dopo la protesta durata giorni, promossa dagli <a href=\"https:\/\/quicosenza.it\/news\/14585\">studenti del liceo di Castrolibero<\/a> che chiedevano di rompere il silenzio e di far luce sui casi di molestie.<\/p>\n<h3>L&#8217;accusa di tentata estorsione, la foto del seno in cambio del voto<\/h3>\n<p>Tra le accuse nei confronti del docente anche la tentata estorsione legata ad una circostanza che risale al mese di giugno del 2018, quando l&#8217;insegnante avrebbe minacciato una studentessa, prospettandole, come afferma la Procura nell&#8217;avviso di conclusione delle indagini &#8220;il <strong>mancato raggiungimento della sufficienza<\/strong> nella sua materia qualora non avesse accondisceso alla richiesta di scattarsi <strong>una foto ritraente il seno<\/strong>, le porgeva il proprio telefono cellulare con la telecamera accesa al fine di costringere la vittima ad assecondare le sue richieste. Evento non verificatosi a causa del rifiuto da parte della ragazza&#8221;. Sempre secondo la Procura, lo stesso professore, in diverse occasioni, avrebbe &#8220;<strong>palpeggiato, sfiorato ed umiliato le studentesse&#8221;.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gli indagati potranno chiedere di essere sentiti o di depositare una memoria difensiva entro 20 giorni. La procura di Cosenza decider\u00e0 poi se procedere con la richiesta di rinvio a giudizio<\/p>\n","protected":false},"author":42,"featured_media":179995,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,564],"tags":[19],"class_list":["post-179994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-castrolibero","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/179994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=179994"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/179994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/179995"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=179994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=179994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=179994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}