{"id":181265,"date":"2022-12-16T09:27:48","date_gmt":"2022-12-16T08:27:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/amendolara-ricorda-lassessore-ilaria-gentile-ad-un-anno-dalla-sua-scomparsa\/"},"modified":"2023-01-25T11:42:19","modified_gmt":"2023-01-25T10:42:19","slug":"489909-amendolara-ricorda-lassessore-ilaria-gentile-ad-un-anno-dalla-sua-scomparsa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/489909-amendolara-ricorda-lassessore-ilaria-gentile-ad-un-anno-dalla-sua-scomparsa\/","title":{"rendered":"Amendolara ricorda l&#8217;assessore Ilaria Gentile ad un anno dalla sua scomparsa"},"content":{"rendered":"<p>AMENDOLARA &#8211; Tutto il paese ricorda l&#8217;assessore comunale alla Cultura, Pubblica istruzione e Famiglia, <strong>Ilaria Gentile<\/strong> ad un <a href=\"https:\/\/quicosenza.it\/news\/16630\">anno dalla sua morte<\/a>. L&#8217;Amministrazione comunale guidata dal sindaco Pasquale Aprile, parteciper\u00e0 domenica alle ore 18 in forma ufficiale, alla<strong> Santa messa che avr\u00e0 luogo nella Parrocchia Madonna della Salute della Marina.<\/strong> Sar\u00e0 il nuovo parroco, don Nicola Mobilio, a celebrare le sacre funzioni.<\/p>\n<p>La <strong>dottoressa Gentile<\/strong>, come \u00e8 noto, si \u00e8 spenta prematuramente un anno fa, in un<strong> lettino dell&#8217;Ospedale &#8220;Madonna delle Grazie&#8221; di Matera<\/strong>, dove si trovava ricoverata da qualche giorno, per il repentino <strong>peggioramento del suo stato di salute<\/strong>, messo a dura prova da un brutto male.<strong> Si \u00e8 addormentata a 33 anni,<\/strong> proferendo una frase che per la Chiesa, ancora oggi, \u00e8 oggetto di studio. Prima di passare a nuova vita, Ilaria infatti, ha pronunciato dinanzi ai familiari e ad altri presenti:<em> &#8220;Lass\u00f9 il Cielo \u00e8 di un azzurro bellissimo. C&#8217;\u00e8 san Francesco e san Michele&#8221;<\/em>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-489912 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/ilaria-gentile-e1644835061908.jpg\" alt=\"\" width=\"312\" height=\"313\" title=\"\"><\/p>\n<p>\u00c8 evidente la sua <strong>forte e sincera religiosit\u00e0<\/strong>, e che il suo passaggio a miglior vita, come hanno rimarcato il v<strong>escovo di Cassano<\/strong> e vice presidente della Cei per il Sud, mons. Francesco Savino e don Nicola Arcuri, \u00e8 stato accompagnato <strong>da due grandi Santi della Chiesa cattolica<\/strong>, che le hanno aperto le porte del Paradiso. A San Michele infatti, come \u00e8 scritto nella Sacra scrittura, rappresentato sempre vicino alla Vergine Maria e protagonista del Giudizio individuale, \u00e8 attribuito il ruolo di psicagogo, cio\u00e8 di colui che conduce le anime nel soggiorno della Pace.<\/p>\n<p>Ilaria, nonostante le <strong>pene<\/strong>, talvolta cruente della <strong>malattia<\/strong>, si \u00e8 sempre <strong>dedicata al prossimo<\/strong>, schierandosi anche nella sua breve ma intensa attivit\u00e0 amministrativa, dalla parte degli umili, degli ammalati, delle persone bisognose e sole. Da parte sua non \u00e8 mai mancato un sorriso contagioso verso un fratello afflitto, o una pacca sulle spalle e una parola di conforto, nei confronti di un bambino, un giovane, un anziano, un uomo o una donna, in quel momento meritevole, pi\u00f9 di ogni altro, di attenzioni e aiuto. <strong>In suo onore, \u00e8 nato anche un gruppo di Preghiera denominato &#8220;Ilaria \u00e8 con noi&#8221;.<\/strong><\/p>\n<p>Il primo cittadino Aprile, peraltro legato alla sfortunata mamma da vincoli fraterni di amicizia, che vanno oltre la semplice politica, e l&#8217;intera Amministrazione comunale hanno voluto dedicare alla giovane donna la sala degli Assessori che si trova al primo piano del Palazzo di Citt\u00e0 in piazza Antonio Sassone, che da quasi un anno porta il suo nome. Nella sala consiliare, il posto che occupava \u00e8 stato &#8220;ritirato&#8221; e non assegnato ad altro consigliere, ma sullo scranno \u00e8 stato sistemato un mazzo di fiori che rester\u00e0 l\u00ec in eterno. <strong>Cos\u00ec Amendolara omagger\u00e0 una delle sue figlie predilette,<\/strong> il cui ricordo resta indelebile nel cuore e nella mente di chi ha avuto il piacere e l&#8217;onore di conoscerla da vicino e trascorrere insieme a lei qualche attimo della propria giornata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La scomparsa dell&#8217;assessore comunale alla Cultura, Pubblica istruzione e Famiglia, a 33 anni. Amendolara vuole ricordarla con una Santa Messa<\/p>\n","protected":false},"author":42,"featured_media":181266,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[19],"class_list":["post-181265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/181265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=181265"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/181265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/181266"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=181265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=181265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=181265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}