{"id":182623,"date":"2022-12-31T09:07:22","date_gmt":"2022-12-31T08:07:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/492214-violenta-rissa-con-coltello-a-corigliano-rossano-arrestati-3-extracomunitari"},"modified":"2022-12-31T09:07:22","modified_gmt":"2022-12-31T08:07:22","slug":"492214-violenta-rissa-con-coltello-a-corigliano-rossano-arrestati-3-extracomunitari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/492214-violenta-rissa-con-coltello-a-corigliano-rossano-arrestati-3-extracomunitari\/","title":{"rendered":"Violenta rissa con coltello a Corigliano Rossano: arrestati 3 extracomunitari"},"content":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; Tre extracomunitari sono stati arrestati dai carabinieri di Corigliano Rossano<strong> per una violenta rissa a colpi di coltelli e bottiglie di vetro.<\/strong><\/p>\n<p>Il tutto \u00e8 successo nella tarda serata di ieri a Schiavonea,<strong> nell\u2019area Quadrato Compagna, dove secondo quanto si \u00e8 appreso, i tre sarebbero anche rimasti feriti e quindi trasferiti in ospedale per essere curati<\/strong> e da qui essere poi condotti al carcere di Castrovillari. Altre persone coinvolte nella rissa sono riuscite a fuggire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella violenta rissa pare siano state coinvolte anche altre persone che per\u00f2 sarebbero riuscite a dileguarsi in tempo prima dell\u2019arrivo dei carabinieri<\/p>\n","protected":false},"author":61,"featured_media":182624,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-182623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/182623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=182623"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/182623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/182624"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=182623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=182623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=182623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}