{"id":182740,"date":"2023-01-08T13:00:00","date_gmt":"2023-01-08T12:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/492515-polfer-andrea-lo-iacono-nuovo-dirigente-compartimento-calabria"},"modified":"2023-01-08T13:00:00","modified_gmt":"2023-01-08T12:00:00","slug":"492515-polfer-andrea-lo-iacono-nuovo-dirigente-compartimento-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/492515-polfer-andrea-lo-iacono-nuovo-dirigente-compartimento-calabria\/","title":{"rendered":"Polfer, Andrea Lo Iacono nuovo dirigente Compartimento Calabria"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Andrea Nicola Lo Iacono \u00e8 <strong>il nuovo dirigente del Compartimento della Polizia ferroviaria della Calabria.<\/strong> Subentra ad <strong>Aurelio Montaruli<\/strong> che, dopo avere salutato il personale dei posti Polfer ed i segretari provinciali delle organizzazioni sindacali della regione, ha incontrato i suoi collaboratori del Compartimento e della Sezione Polfer di Villa San Giovanni, ai quali, riferisce un comunicato diffuso dalla Questura di Reggio Calabria, <strong>&#8220;ha espresso la sua gratitudine per l&#8217;ottimo lavoro svolto nel corso dell&#8217;anno che sta per terminare&#8221;.<\/strong><\/p>\n<p>&#8220;Il dottore Montaruli &#8211; si afferma ancora nella nota &#8211; assumer\u00e0 a partire del prossimo 9 gennaio la direzione del Compartimento di Polizia ferroviaria per la Puglia, la Basilicata ed il Molise, con sede a Bari, come disposto dal Capo della Polizia, prefetto Lamberto Giannini&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andrea Nicola Lo Iacono \u00e8 il nuovo dirigente del Compartimento della Polizia ferroviaria della Calabria subentra ad Aurelio Montaruli<\/p>\n","protected":false},"author":61,"featured_media":182741,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-182740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/182740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=182740"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/182740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/182741"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=182740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=182740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=182740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}