{"id":182831,"date":"2023-01-04T15:22:42","date_gmt":"2023-01-04T14:22:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/492776-dalla-regione-arriva-lok-per-il-complemento-del-piano-di-sviluppo-rurale"},"modified":"2023-01-04T15:22:42","modified_gmt":"2023-01-04T14:22:42","slug":"492776-dalla-regione-arriva-lok-per-il-complemento-del-piano-di-sviluppo-rurale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/492776-dalla-regione-arriva-lok-per-il-complemento-del-piano-di-sviluppo-rurale\/","title":{"rendered":"Dalla Regione arriva l\u2019ok per il complemento del Piano di sviluppo rurale"},"content":{"rendered":"<p>CATANZARO &#8211; La Regione Calabria ha dato il via al nuovo Piano di sviluppo rurale 2023\/2027, attraverso l\u2019<strong>approvazione del Complemento di programmazione per lo sviluppo rurale<\/strong> (Csr), lo strumento essenziale per l\u2019attuazione dei piani strategici della politica agricola comune. Il documento, che declina<strong> le scelte regionali gi\u00e0 inserite nel PSP 2023-2027<\/strong> (Piano strategico PAC), approvato dalla Commissione Europea il 2 Gennaio, \u00e8 stato adottato nei giorni scorsi \u2013 <strong>su proposta dell\u2019assessore all\u2019Agricoltura, Gianluca Gallo<\/strong>, dalla Giunta regionale presieduta da Roberto Occhiuto.<\/p>\n<p>\u00abSi tratta \u2013 spiega l\u2019assessore Gallo \u2013 di un passaggio fondamentale nella d<strong>efinizione degli scenari futuri della nostra agricoltura<\/strong>, dal momento che attraverso il complemento di programmazione si introducono importanti elementi di novit\u00e0 rispetto al passato, per un Psr che potr\u00e0 contare su risorse significative: <strong>la spesa pubblica destinata alla Calabria ammonta a 781 milioni, che si aggiungono ai 363 milioni<\/strong> derivanti dal prolungamento del PSR 2014-2022, per un totale 1.144 milioni di euro, con un incremento nel settennio di 61 milioni in valore assoluto rispetto alla passata programmazione 2014-2020\u00bb. L\u2019approvazione del Complemento <strong>si inserisce indicando le priorit\u00e0, le disposizioni specifiche e le modalit\u00e0 attuative individuate per rispondere in maniera adeguata<\/strong> alle esigenze e peculiarit\u00e0 di ciascun territorio, anche con l\u2019obiettivo di semplificare l\u2019accesso alle informazioni del Piano strategico Pac (PsP) per i portatori di interesse calabresi.<\/p>\n<p>\u00abLa struttura del documento \u2013 sottolinea l\u2019Assessore Gallo \u2013 frutto del lavoro del Dipartimento e oggetto di ampia condivisione con il partenariato, <strong>\u00e8 stato impostato privilegiando una comunicazione pi\u00f9 trasparente ed efficace<\/strong> relativa agli elementi essenziali della futura politica regionale di sviluppo rurale\u00bb. Per questo nella sua prima parte il Csr ricostruisce \u2013 a beneficio proprio del partenariato e del grande pubblico \u2013 le fasi di lavoro, le scelte strategiche effettuate e le risorse finanziarie mobilitate. Nella seconda, invece,<strong> trovano posto la rappresentazione sintetica delle schede di intervento, insieme con il cronoprogramma dell\u2019attuazione<\/strong>, cos\u00ec da poter offrire ai potenziali destinatari dei bandi uno strumento di immediata utilit\u00e0 operativa. Per i necessari approfondimenti, comunque, il CSR contiene i rimandi alle pertinenti sezioni del PSP. Il Csr, dopo aver ricevuto il via libera della Giunta regionale, \u00e8 stato trasmesso all\u2019autorit\u00e0 di gestione nazionale, presso <strong>il Ministero dell\u2019agricoltura, della sovranit\u00e0 alimentare e delle foreste<\/strong>. Esso, soggetto ad aggiornamento periodico sulla base delle modifiche strategiche ed attuative decise dalla Regione, \u00e8 pubblicato sui portali web regionali e nazionali, in modo tale da massimizzarne la visibilit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al via il nuovo Psr 2023-2027, Gallo: \u00abstrumento essenziale per l\u2019attuazione dei piano strategici regionali\u00bb<\/p>\n","protected":false},"author":61,"featured_media":182832,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-182831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/182831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=182831"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/182831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/182832"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=182831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=182831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=182831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}