{"id":182880,"date":"2023-01-05T16:30:22","date_gmt":"2023-01-05T15:30:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/492909-il-sindaco-di-cassano-scrive-a-mattarella-blocchi-la-legge-sullautonomia"},"modified":"2023-01-05T16:30:22","modified_gmt":"2023-01-05T15:30:22","slug":"492909-il-sindaco-di-cassano-scrive-a-mattarella-blocchi-la-legge-sullautonomia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/492909-il-sindaco-di-cassano-scrive-a-mattarella-blocchi-la-legge-sullautonomia\/","title":{"rendered":"Il sindaco di Cassano scrive a Mattarella: \u00abblocchi la legge sull&#8217;autonomia\u00bb"},"content":{"rendered":"<p>CASSANO ALLO IONIO (CS) &#8211; Si torna a discutere nuovamente di autonomia differenziata in Calabria che torna a tenere banco, dopo l&#8217;avvertimento del ministro <strong><a href=\"https:\/\/quicosenza.it\/news\/16744\" target=\"_blank\" rel=\"noopener\">Calderoli, pronto a querelare<\/a> chiunque definisca il provvedimento lo &#8216;Spacca Italia&#8217;. <\/strong>Stavolta l&#8217;appello giunge dal cosentino. Il sindaco di Cassano allo Ionio, <strong>Gianni Papasso, ha scritto al Presidente della Repubblica<\/strong>, Sergio Mattarella, chiedendogli di intervenire p<strong>er bloccare la proposta di legge sull&#8217;Autonomia differenziata<\/strong>.<\/p>\n<p>Papasso fa parte della rete &#8220;Recovery Sud&#8221; che si oppone all&#8217;approvazione della normativa. Il sindaco Papasso, nella missiva, chiede al Capo dello Stato &#8220;di suggerire alle forze politiche di prevedere, come primo punto della loro agenda politica, misure che possano<strong> ridurre le distanze tra i diversi territori del Paese<\/strong>, ed in particolare tra Nord e Sud.<\/p>\n<p>Un<strong> gap<\/strong> &#8211; sottolinea il sindaco di Cassano &#8211; che si basa <strong>su indicatori<\/strong> come la mortalit\u00e0 infantile, la diversa aspettativa di vita (minore di 3,7 anni per un bambino di Caltanissetta rispetto a un coetaneo di Firenze), il ricorso a cure mediche fuori regione, il tasso di disoccupazione, l&#8217;emigrazione intellettuale, la dotazione infrastrutturale, l&#8217;occupazione femminile, la qualit\u00e0 del sistema scolastico e universitario. E di astenersi dall&#8217;insistere su <strong>un progetto di autonomia differenziata che potr\u00e0 soltanto acuirle<\/strong>&#8220;.<\/p>\n<p>&#8220;Le saremmo grati &#8211; scrive ancora Papasso rivolto al presidente Mattarella &#8211; se volesse ricevere la nostra rete di sindaci &#8216;Recovery Sud&#8217;, che per la prima volta nella storia d&#8217;Italia sta riunendo amministratori del Mezzogiorno decisi a promuovere un&#8217;azione congiunta per il superamento degli storici divari, affermando il valore della coesione nazionale e proponendo soluzioni a partire da un confronto fondato su un&#8217;analisi pi\u00f9 puntuale dei bisogni dei nostri territori. L&#8217;obiettivo \u00e8 quello di dire<strong> un forte &#8216;no&#8217; all&#8217;autonomia<\/strong>, superando insieme i divari che si sono creati nel corso del tempo tra Nord e Sud&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La proposta di legge torna a far discutere dopo l&#8217;avvertimento di Calderoli pronto a querelare chiunque la definisca &#8216;Spacca-Italia&#8217;<\/p>\n","protected":false},"author":58,"featured_media":182881,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-182880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/182880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=182880"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/182880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/182881"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=182880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=182880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=182880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}