{"id":182922,"date":"2023-01-07T16:00:34","date_gmt":"2023-01-07T15:00:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/493063-carceri-la-struttura-corigliano-rossano-e-sovraffollata-e-il-personale-non-basta"},"modified":"2023-01-07T16:00:34","modified_gmt":"2023-01-07T15:00:34","slug":"493063-carceri-la-struttura-corigliano-rossano-e-sovraffollata-e-il-personale-non-basta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/493063-carceri-la-struttura-corigliano-rossano-e-sovraffollata-e-il-personale-non-basta\/","title":{"rendered":"Carceri: la struttura Corigliano Rossano \u00e8 sovraffollata e il personale non basta"},"content":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; &#8220;Nel corso di un cordiale incontro con il <strong>direttore<\/strong> della casa di reclusione di Corigliano Rossano, <strong>Maria Luisa Mendicino<\/strong>, ho potuto constatare la realt\u00e0 carceraria ed ascoltare le grandi difficolt\u00e0 che quotidianamente affrontano le donne e gli uomini del corpo di Polizia penitenziaria&#8221;. \u00c8 quanto afferma il senatore <strong>Ernesto Rapani<\/strong>, componente della <strong>Commissione Giustizia<\/strong>, che ha fatto visita al <strong>polo penitenziario di Corigliano Rossano<\/strong>. &#8220;Ho accertato la grande dignit\u00e0 &#8211; ha aggiunto Rapani &#8211; con la quale sono trattati i detenuti e le attivit\u00e0 che possono svolgere all&#8217;interno della casa di reclusione, che vanta importantissimi laboratori in cui vengono impiegati dei detenuti come quello di falegnameria, con strumentazioni all&#8217;avanguardia ma purtroppo sotto utilizzato, e quello di ceramica. Il carcere di Rossano presenta anche un importante offerta didattica, con la possibilit\u00e0 di frequentare le scuole di ogni grado fino all&#8217;Universit\u00e0, grazie ad un <strong>protocollo d&#8217;intesa<\/strong> con l&#8217;Unical. <strong>Non mancano, per\u00f2, i problemi<\/strong>&#8220;.<\/p>\n<p>&#8220;Ad oggi la casa di reclusione costruita nel 2000 &#8211; sostiene il parlamentare di FdI &#8211; \u00e8 <strong>sovraffollata<\/strong>. Ospita una popolazione di 305 detenuti a fronte di una capienza di 263. \u00c8 composta da un reparto media sicurezza che custodisce 74 detenuti, un reparto alta sicurezza AS2 strutturato su due piani detentivi che ospita, al momento, 8 detenuti ristretti per reati attinenti al terrorismo di matrice islamica, ed un reparto alta sicurezza AS3, su tre piani, con 215 detenuti, tutti reclusi per pene definitive sopra i cinque anni, molti dei quali ergastolani e pluriergastolani ed in regime di 41 bis. Per tutti questi detenuti la pianta organica della Polizia penitenziarie \u00e8 fortemente inadeguata. Prevederebbe 153 unit\u00e0 ma sono solo 66 i poliziotti penitenziari disponibili alla turnazione, compresi il comandante e gli ispettori. Appare, dunque, evidente il vulnus che esiste sotto il profilo della sicurezza anche per via dei tanti detenuti affetti patologie psichiatriche ed il grave sovraccarico di lavoro su un personale che si caratterizza per la sua anzianit\u00e0 di servizio&#8221;. &#8220;Dei problemi della casa di reclusione di Corigliano Rossano me ne far\u00f2 carico &#8211; sottolinea ancora Rapani &#8211; riferendone alla Commissione Giustizia, della quale faccio parte, al sottosegretario Andrea Delmastro e al Ministro Nordio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il senatore Ernesto Rapani, componente della Commissione Giustizia: &#8220;pesa il deficit sulla presenza polizia penitenziaria ed \u00e8 a rischio la sicurezza&#8221;<\/p>\n","protected":false},"author":42,"featured_media":182923,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[19],"class_list":["post-182922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/182922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=182922"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/182922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/182923"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=182922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=182922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=182922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}