{"id":183109,"date":"2023-01-11T14:00:31","date_gmt":"2023-01-11T13:00:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/493541-a-san-giovanni-in-fiore-il-primo-concorso-regionale-della-pitta-mpigliata"},"modified":"2023-01-11T14:00:31","modified_gmt":"2023-01-11T13:00:31","slug":"493541-a-san-giovanni-in-fiore-il-primo-concorso-regionale-della-pitta-mpigliata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/493541-a-san-giovanni-in-fiore-il-primo-concorso-regionale-della-pitta-mpigliata\/","title":{"rendered":"A San Giovanni in Fiore il primo concorso regionale della pitta mpigliata"},"content":{"rendered":"<p>SAN GIOVANNI IN FIORE (CS) \u2013 Tutto pronto per il &#8216;<strong>pitta mpigliata contest&#8217;<\/strong>, la prima edizione in Calabria del concorso regionale della pitta mpigliata fatta in casa. Sono aperte le iscrizioni per l\u2019evento che si terr\u00e0 <strong>sabato 14 gennaio<\/strong>, dalle ore 9, a San Giovanni in Fiore, presso il Centro Florens, Istituto Professionale Statale per i Servizi Alberghieri e della Ristorazione \u2013 ITS Leonardo da Vinci. Lo scopo della manifestazione \u00e8 quello di <strong>promuovere, valorizzare e incentivare la cultura della pitta mpigliata<\/strong> all\u2019interno dell\u2019intero territorio regionale. Tra gli ospiti ci sar\u00e0 anche lo chef <strong>Alessandro Circiello.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-493543 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/01\/pitta-mpigliata-contest-regionale.jpg\" alt=\"\" width=\"562\" height=\"645\" title=\"\"><\/p>\n<p>Il concorso ha come scopo quello di mettere a confronto le diverse <strong>ricette e tecniche di lavorazione della pitta mpigliata<\/strong>, attraverso una <strong>allegra e serena competizione<\/strong> che vede impegnati estimatori ed amatori di questo straordinario dolce e su cui si poggeranno le basi per avviare un disciplinare di produzione. La realizzazione della pitta mpigliata da parte di un appassionato, amante di questa leccornia, \u00e8 espressione artistica che coinvolge sentimenti ed emozioni. Condividere tutto ci\u00f2 &#8211; e confrontarsi nelle diverse tecniche e metodologie di preparazione del dolce &#8211; \u00e8 un grande momento di confronto, di scambio culturale e di conoscenza delle diverse tradizioni.<\/p>\n<p>L\u2019evento \u00e8 realizzato in collaborazione con l\u2019Associazione Cuochi Regionale, AMIRA Calabria, l\u2019Istituto Professionale Statale per i Servizi Alberghieri e della Ristorazione \u2013 ITS Leonardo da Vinci di San Giovanni in Fiore, l\u2019associazione delle proloco regionale e da diverse altre associazioni. Patrocinato da diversi enti tra i quali la Regione Calabria. Per informazioni su iscrizioni e regolamento <strong><a href=\"https:\/\/quicosenza.it\/news\/16769\">CLICCA QUI<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; possibile iscriversi all\u2019evento che si terr\u00e0 sabato presso il Centro Florens, Istituto Professionale Statale per i Servizi Alberghieri e della Ristorazione \u2013 ITS Leonardo da Vinci<\/p>\n","protected":false},"author":42,"featured_media":183110,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-183109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=183109"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183110"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=183109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=183109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=183109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}