{"id":183117,"date":"2023-01-11T11:51:53","date_gmt":"2023-01-11T10:51:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/493562-si-e-spento-a-celico-il-noto-criminologo-francesco-bruno-aveva-74-anni"},"modified":"2023-01-11T11:51:53","modified_gmt":"2023-01-11T10:51:53","slug":"493562-si-e-spento-a-celico-il-noto-criminologo-francesco-bruno-aveva-74-anni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/493562-si-e-spento-a-celico-il-noto-criminologo-francesco-bruno-aveva-74-anni\/","title":{"rendered":"Si \u00e8 spento a Celico il noto criminologo Francesco Bruno, aveva 74 anni"},"content":{"rendered":"<p>CELICO (CS) &#8211; \u00c8 morto questa mattina, all&#8217;et\u00e0 di 74anni, nella sua terra nativa a Celico, <strong>il professore Francesco Bruno, medico e criminologo di fama internazionale<\/strong> che con il suo sapere ha dato lustro alla sua amata Calabria. Bruno era nato nel centro presilano il 10 maggio del 1948. <strong>A dare notizia della scomparsa il sindaco di Celico, Matteo Lettieri. <\/strong>Il Professor Francesco Bruno era un luminare impegnato nella risoluzione dei pi\u00f9 efferati delitti italiani e collabor\u00f2 con vari ministeri per lo studio delle droghe. Nei primi anni &#8217;80, su impulso di Vincenzo Parisi, allora vertice del SISDE, pubblica il primo studio universitario che <strong>collega gli omicidi commissionati al &#8220;Mostro di Firenze&#8221; con l&#8217;esoterismo e il fine sacrificale. <\/strong>Francesco Bruno, criminologo di professione, fece parte del <strong>collegio difensivo di Pietro Pacciani<\/strong> come consulente di parte. Docente di Criminologia e di Psicopatologia Forense in varie sedi universitarie fu anche docente straordinario di Pedagogia Sociale presso l&#8217;Universit\u00e0 degli Studi di Salerno e titolare della cattedra di scienze psichiatriche all&#8217;universit\u00e0 &#8220;La Sapienza&#8221; di Roma\u00a0. Diresse la sua attenzione, soprattutto su tematiche politiche, sociali, morali e di formazione per riproporre la centralit\u00e0 e la soggettivit\u00e0 dell&#8217;uomo che la societ\u00e0 attuale delle nuove tecnologie dell\u2019informazione e comunicazione sembra ridurre<strong>. I funerali saranno celebrati a Celico<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/16771\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-493570\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/01\/Francesco-Bruno-605x400.jpg\" alt=\"Francesco Bruno\" width=\"605\" height=\"400\" title=\"\"><\/a><\/p>\n<h3><strong>Francesco Bruno tra i massimi esperti di criminologia<\/strong><\/h3>\n<p>Dal 1979 al 1987 Bruno fu un funzionario, e poi direttore di sezione, alla presidenza del Consiglio dei Ministri.\u00a0Nel 1987 divenne professore di Criminologia e medicina forense alla Sapienza, negli anni &#8217;90 collabor\u00f2 nuovamente con vari ministeri contro la criminalit\u00e0 mafiosa e la lotta alla droga.\u00a0 <strong>\u00c8 stato, inoltre, in vari programmi televisivi dedicati a serial killer,<\/strong> tra cui Delitti (LA7), Maurizio Costanzo Show (Canale 5) ma sopratutto fu un ospite fisso per un decennio a Porta a Porta su Rai1 condotto da bruno Vespa occupandosi, tra l&#8217;altro, anche di gialli e crimini che hanno segnato la storia italiana come il delitto di Cogne. Dal 2010 si occup\u00f2 anche del caso di <a title=\"\u2018Non smettete di cercarla\u2019, l\u2019appello della sorella di Rina Pennetti scomparsa nel 2009\" href=\"https:\/\/quicosenza.it\/news\/16772\" target=\"_blank\" rel=\"noopener\">Rina Pennetti<\/a>,<strong> giovane donna di 33 anni scomparsa a Spezzano della Sila<\/strong>.\u00a0Francesco Bruno fu anche direttore scientifico del master in Scienze forensi dell\u2019Universit\u00e0 La Sapienza di Roma e investigatore privato Edi Ciesco che ha lavorato negli ultimi anni nei casi pi\u00f9 controversi e difficili come l\u2019omicidio di Natalia Gonzales Fernandez, la cameriera colombiana dipendente del centro commerciale Le Torri d&#8217;Europa, uccisa il 22 aprile 2009 a Sincelejo o quello di Ramon Polentarutti, scomparso il 14 aprile 2011: i suoi resti sono quelli rinvenuti nel novembre scorso nelle griglie delle vasche di raffreddamento della centrale A2A.\u00a0<strong>Bruno lascia la sua compagna Simonetta Costanzo, docente universitaria all&#8217;Unical e il figlio Alfredo<\/strong>.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Flettieri9%2Fposts%2Fpfbid0y6ETCwbToDeiyKzuMBKuQc5sjEDLyj8569nuj9UDL1iHnBeJdgCGV3iSTg4BefUpl&#038;show_text=true&#038;width=500\" width=\"500\" height=\"552\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe><br \/>\n&nbsp;<\/p>\n<h3>Il sindaco di Cosenza &#8220;Bruno vanto ed orgoglio per tutta la Calabria&#8221;<\/h3>\n<p>Cordoglio, per la scomparsa del prof. Francesco Bruno, \u00e8 stato espresso anche dal sindaco di Cosenza Caruso &#8220;Il Prof.Francesco Bruno \u00e8 stato<strong> vanto ed orgoglio per Cosenza, la sua provincia e la Calabria intera<\/strong> e tutto questo ancor prima che la sua notoriet\u00e0 fosse notevolmente accresciuta dalle numerose trasmissioni televisive cui abitualmente veniva invitato e partecipava. Il fatto che oggi non sia pi\u00f9 tra noi ci rattrista e ci priva di una <strong>grande figura nell&#8217;ambito degli studi di criminologia,<\/strong> settore nel quale ha rappresentato una vera eccellenza e di profilo non solo nazionale. Il Prof.Bruno \u2013 ha aggiunto Franz Caruso \u2013 \u00e8 stato non solo un criminologo di spessore, ma anche<strong> uomo di grande cultura e apprezzatissimo docente dell&#8217;Universit\u00e0<\/strong> &#8220;La Sapienza&#8221; di Roma e dell&#8217;Universit\u00e0 della Calabria&#8221;, distinguendosi nell&#8217;ambito della medicina forense e come studioso attento di alcuni tra i casi pi\u00f9 intricati della cronaca nazionale. L&#8217;Amministrazione comunale tutta \u2013 ha aggiunto il primo cittadino \u2013 partecipa al dolore che ha colpito i familiari, anzitutto la moglie, Prof.ssa Simonetta Costanzo, ed il figlio Alfredo, ai quali vanno le nostre pi\u00f9 sentite condoglianze&#8221;. Un messaggio di cordoglio \u00e8 stato indirizzato dal Sindaco Franz Caruso, per la scomparsa di Francesco Bruno, anche all&#8217;Amministrazione comunale e a tutta la comunit\u00e0 di Celico, luogo d&#8217;origine del criminologo&#8221;.<\/p>\n<h3>&#8220;Un medico onesto&#8221;<\/h3>\n<p>Numerosi i messaggi di cordoglio tra<strong> i quali la deputata della Lega Simona Loizzo<\/strong>: &#8220;la tristezza mi assale. Un luminare nella scienza della medicina legale. <strong>Un medico onesto, competente. Una persona mite, un calabrese che ha reso onore alla sua terra, la sua Celico<\/strong> che ha amato oltre ogni confine. Siamo pi\u00f9 poveri &#8211; scrive Loizzo su Facebook &#8211; e senza il suo sapere sebbene le testimonianze scientifiche ed umane colmeranno, sia pure in parte, il vuoto che lascia. La Calabria gli deve molto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Addio a Francesco Bruno \u00abuncalabrese che ha reso onore alla sua terra, la sua Celico che ha amato oltre ogni confine\u00bb<\/p>\n","protected":false},"author":61,"featured_media":183118,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-183117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=183117"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183118"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=183117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=183117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=183117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}