{"id":183151,"date":"2023-01-12T05:59:28","date_gmt":"2023-01-12T04:59:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/493655-medicina-allunical-sindaco-catanzaro-ricorreremo-al-tar"},"modified":"2023-01-12T05:59:28","modified_gmt":"2023-01-12T04:59:28","slug":"493655-medicina-allunical-sindaco-catanzaro-ricorreremo-al-tar","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/493655-medicina-allunical-sindaco-catanzaro-ricorreremo-al-tar\/","title":{"rendered":"Medicina all&#8217;Unical, sindaco Catanzaro \u00abricorreremo al Tar\u00bb"},"content":{"rendered":"<p>CATANZARO &#8211; &#8220;Il modo con cui si sta procedendo sulla questione universitaria<strong> apre una pericolosa guerra di campanile<\/strong>. Quanto sta avvenendo \u00e8 inaccettabile e probabilmente illegittimo. Per questo motivo, ci muoveremo attraverso la giustizia amministrativa per evitarlo. E seguiremo lo stesso metodo se non vedremo segnali positivi nella realizzazione dell&#8217;Azienda ospedaliera unica integrata da parte del presidente della Regione, Occhiuto&#8221;.<\/p>\n<p>Il sindaco di Catanzaro, Nicola Fiorita, ieri ha convocato un incontro in Comune sulla vicenda dell&#8217;apertura a Cosenza di una facolt\u00e0 di Medicina. &#8220;<strong>Credo che sia la prima volta<\/strong> &#8211; ha aggiunto Fiorita &#8211; <strong>che un sindaco chiama a raccolta gli ordini professionali, gli intellettuali, le forze della societ\u00e0 civile<\/strong>. Questo incontro si collega alla seduta aperta del Consiglio comunale, in programma luned\u00ec 16 gennaio, durante la quale credo che verr\u00e0 dato al sindaco un mandato per tutelare la citt\u00e0. Deve essere la citt\u00e0 a dirmi cosa bisogna fare. Anche in merito all&#8217;esigenza di condurre una battaglia per difendere le prerogative di Catanzaro, una citt\u00e0 civile, dialogante e serena, che ha sempre cercato di rapportarsi in maniera ragionevole con il resto del territorio. Quello che chiediamo \u00e8 soltanto ragionevolezza ed equit\u00e0 delle scelte che vengono fatte&#8221;.<\/p>\n<p>Per il primo cittadino &#8220;in questo periodo si <strong>sono sovrapposte due vicende<\/strong> che rendono tutto pi\u00f9 complicato e che bisognerebbe, invece, tenere separate: <strong>l&#8217;integrazione delle aziende &#8216;Pugliese Ciaccio&#8217; e &#8216;Dulbecco<\/strong>&#8216;, che non pu\u00f2 essere pi\u00f9 rimandata, e la brusca accelerazione che \u00e8 stata impressa sull&#8217;istituzione della<strong> facolt\u00e0 di Medicina a Cosenza<\/strong>. <strong>Bisogna separare le due cose.<\/strong> Chiediamo che la questione universitaria venga affrontata in modo complessivo e ragionevole. Il sistema di formazione universitaria deve tenere conto delle esigenze di tutti i territori. Se riteniamo che si possa dare ai giovani calabresi la possibilit\u00e0 di studiare in Calabria, ampliando l&#8217;offerta formativa di Medicina, questo deve valere anche per Architettura a Catanzaro ed Ingegneria a Reggio Calabria&#8221;. &#8220;Se si procede solo per un territorio &#8211; ha detto ancora il Sindaco di Catanzaro &#8211; si scoperchia il vaso di Pandora dei campanilismi e delle lotte giocate sui rapporti di forza e non sulla politica tra i vari territori. Se sar\u00e0 necessario da parte mia chiedere un &#8216;patto per la citt\u00e0&#8217;, allargando la maggioranza, lo far\u00f2 volentieri, perch\u00e9 tutti dobbiamo fare qualcosa per rendere Catanzaro pi\u00f9 forte e superare la debolezza politica che l&#8217;ha caratterizzata, sedimentandosi e crescendo negli anni&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continua l&#8217;opposizione da parte del Comune di Catanzaro alla decisione di istituire la facolt\u00e0 di Medicina all&#8217;Universit\u00e0 della Calabria:  \u00abci muoveremo attraverso la giustizia amministrativa per evitarlo\u00bb<\/p>\n","protected":false},"author":42,"featured_media":183152,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-183151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=183151"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183152"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=183151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=183151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=183151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}