{"id":183182,"date":"2023-01-12T14:00:21","date_gmt":"2023-01-12T13:00:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/493758-calabrese-ricercato-per-bancarotta-arrestato-sulle-montagne-svizzere"},"modified":"2023-01-12T14:00:21","modified_gmt":"2023-01-12T13:00:21","slug":"493758-calabrese-ricercato-per-bancarotta-arrestato-sulle-montagne-svizzere","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/493758-calabrese-ricercato-per-bancarotta-arrestato-sulle-montagne-svizzere\/","title":{"rendered":"Calabrese ricercato per bancarotta, arrestato sulle montagne svizzere"},"content":{"rendered":"<p>PERUGIA &#8211; E&#8217; stato arrestato sulle montagne svizzere un uomo di<strong> 54 anni<\/strong>, <strong>originario del catanzarese<\/strong>, ricercato dal 2020 con l&#8217;accusa di <strong>bancarotta fraudolenta<\/strong> aggravata e che aveva fatto perdere le sue tracce in Italia dall&#8217;aprile del 2013. Il soggetto \u00e8 stato bloccato dalla <strong>polizia elvetica il 9 gennaio nella citt\u00e0 di Solothurn<\/strong>. Secondo la magistratura perugina la presunta <strong>attivit\u00e0 illecita aveva fruttato all&#8217;uomo oltre mezzo milione di euro.<\/strong><\/p>\n<p>L&#8217;attivit\u00e0 investigativa che ha portato a rintracciarlo \u00e8 stata avviata dalla Procura generale di Perugia, guidata da Sergio Sottani, e in particolare dall&#8217;ufficio Servizio di indagine costituito da un appartenente alla polizia penitenziaria. Il provvedimento di esecuzione delle pene concorrenti, emesso dalla Procura generale &#8211; si legge in un suo comunicato -, disponeva a carico dell&#8217;uomo <strong>una pena di cinque anni e 11 mesi di reclusione<\/strong> per <strong>reati commessi tutti nell&#8217;ascolano tra il 1997 e il 2010.<\/strong><\/p>\n<p>Il procedimento \u00e8 poi approdato a Perugia per questioni procedurali. Dalle indagini \u00e8 per\u00f2 emerso che l&#8217;uomo era per\u00f2 riuscito a <strong>lasciare l&#8217;Italia dal 2013<\/strong> a bordo di <strong>un&#8217;auto con targa svizzera<\/strong> e in compagnia di una <strong>donna elvetica<\/strong>. Notizie comunicate all&#8217;Interpol di Roma che, tramite il collaterale svizzero, hanno portato all&#8217;arresto dell&#8217;uomo. Il cinquantaquattrenne ora \u00e8 in attesa di essere estradato in Italia per scontare la pena inflitta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;uomo, di 54 anni, aveva fatto perdere le sue tracce in Italia dall&#8217;aprile del 2013. Rintracciato grazie alle indagini della Procura generale di Perugia<\/p>\n","protected":false},"author":42,"featured_media":183183,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-183182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=183182"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183182\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183183"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=183182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=183182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=183182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}