{"id":18320,"date":"2013-02-23T11:16:55","date_gmt":"2013-02-23T10:16:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=18320"},"modified":"2023-01-17T13:16:18","modified_gmt":"2023-01-17T12:16:18","slug":"6644-cosenza-i-tifosi-trattano-con-il-sultano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6644-cosenza-i-tifosi-trattano-con-il-sultano\/","title":{"rendered":"Cosenza, i tifosi &#8220;trattano&#8221; con il sultano"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Mentre la squadra si allena, i tifosi studiano l&#8217;&#8230; arabo. <strong>Quando i tifosi non stanno a guardare. <\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong>Vista la forte contingenza economica e l\u2019assenza di una certezza futura del calcio cosentino, un nutrito gruppo di supporters rossobl\u00f9 hanno dato il via libera all\u2019operazione \u201cSalva Cosenza\u201d. Non \u00e8 una bufala, ma \u00e8 l\u2019idea di alcuni tifosi, in primis Antonio Bruno e l\u2019avvocato Antonello Aprile, legale del foro cittadino, nonch\u00e8 tifosissimo della squadra silana, che hanno pensato bene di arrivare a contattare, niente di meno, il sultano del Quatar Hamad Bin Khalifa Al-Thani.<\/strong> Sono riusciti a trovare il giusto canale per arrivare all\u2019Emiro, tramite l\u2019 ambasciata romana. Perch\u00e8 proprio l\u2019Emiro del Quatar? \u201cSiamo in un punto di non ritorno, non riusciamo a vedere un futuro certo per il Cosenza\u201d, spiega il legale cosentino. \u201cNoi tifosi non staremo con le mani in mano, tentiamo questa strada, oserei dire, della disperazione. Non ci illudiamo, ma provare non costa nulla. Certo sar\u00e0 molto difficile questa operazione. L\u2019Emiro del Quatar, \u00e8 inutile dirlo, \u00e8 uno dei pi\u00f9 ricchi al mondo, con un patrimonio personale di quasi 5 miliardi di dollari, \u00e8 proprietario dell\u2019emittente araba Al Jazeera, gestisce il fondo monetario del Quatar. <strong>Abbiamo pensato a lui &#8211; spiega l&#8217;avvocato Antonello Aprile &#8211; perch\u00e9 ha stretti rapporti con l\u2019Italia e, soprattutto ha grande rispetto e passione per il mondo del calcio. La sua societ\u00e0 \u00e8 padrona del Paris Saint Germain, del Malaga, \u00e8 una importante sponsorizzazione del Barcellona, sta cercando di acquisire una squadra importante anche in Premier. Insomma il calcio \u00e8 uno dei suoi interessi primari. Abbiamo illustrato la nostra situazione calcistica, il blasone e le potenzialit\u00e0 che pu\u00f2 offrire il Cosenza per creare un progetto ambizioso. Non vogliamo illudere nessuno, non ci resta che aspettare una sua risposta, che tutti speriamo sia positiva.\u201d <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Mentre la squadra si allena, i tifosi studiano l&#8217;&#8230; arabo. Quando i tifosi non stanno a guardare.<\/p>\n","protected":false},"author":22,"featured_media":18321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-18320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=18320"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/18321"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=18320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=18320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=18320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}