{"id":183216,"date":"2023-01-13T06:57:43","date_gmt":"2023-01-13T05:57:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/493848-caro-benzina-picchi-in-calabria-e-in-puglia"},"modified":"2023-01-13T06:57:43","modified_gmt":"2023-01-13T05:57:43","slug":"493848-caro-benzina-picchi-in-calabria-e-in-puglia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/493848-caro-benzina-picchi-in-calabria-e-in-puglia\/","title":{"rendered":"Caro-benzina, picchi in Calabria e in Puglia"},"content":{"rendered":"<p>ROMA &#8211; Il gasolio servito viaggia ormai stabilmente a 2,4 euro al litro in molte regioni italiane. Non si tratta certo del prezzo medio nazionale, ma \u00e8 indicativo del fatto che i prezzi alla pompa siano ancora molto elevati. E chi decidesse di regalare al proprio motore diesel un pieno di carburante ad alta prestazione dovr\u00e0 prepararsi a sborsare fino a pi\u00f9 di 2,7 euro a Mazara del Vallo, in Sicilia e poco meno sulla Messina-Palermo (2,622).<\/p>\n<p>&#8220;Le accise per ora non scendono. Ma il governo \u00e8 pronto ad intervenire quando ci saranno maggiori incassi dall&#8217;Iva&#8221;. Lo annuncia la premier <strong>Giorgia Meloni<\/strong> cercando di placare la tensione salita alle stelle dopo le misure decise dall&#8217;esecutivo contro i rincari. Gli interventi non vanno gi\u00f9 ai gestori che scelgono la strada dello scontro aperto: vanno all&#8217;attacco contro l'&#8221;ondata di fango&#8221;, lamentano, gettata sulla categoria e proclamano\u00a0<strong>due giornate di sciopero\u00a0<\/strong>a fine mese. Intanto<strong>\u00a0i gestori hanno annunciato uno sciopero per il 25 e 26 gennaio<\/strong>, con presidio sotto Montecitorio. L&#8217;obiettivo \u00e8 &#8220;porre fine a questa &#8216;ondata di fango&#8217; contro una categoria di onesti lavoratori e cercare di ristabilire la verit\u00e0&#8221;, spiegano unitariamente Faib-Confesercenti, Fegica, Figisc-Confcommercio, che accusano il governo di aumentare il prezzo dei carburanti, scaricando &#8220;la responsabilit\u00e0 sui gestori&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meloni: \u00able accise per ora non scendono. Ma il governo \u00e8 pronto ad intervenire quando ci saranno maggiori incassi dall&#8217;Iva\u00bb<\/p>\n","protected":false},"author":61,"featured_media":183217,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-183216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=183216"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183217"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=183216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=183216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=183216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}