{"id":183242,"date":"2023-01-13T12:53:02","date_gmt":"2023-01-13T11:53:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/493903-antenna-5g-a-sibari-il-sindaco-di-cassano-blocca-i-lavori-timori-per-elettrosmog"},"modified":"2023-01-13T12:53:02","modified_gmt":"2023-01-13T11:53:02","slug":"493903-antenna-5g-a-sibari-il-sindaco-di-cassano-blocca-i-lavori-timori-per-elettrosmog","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/493903-antenna-5g-a-sibari-il-sindaco-di-cassano-blocca-i-lavori-timori-per-elettrosmog\/","title":{"rendered":"Antenna 5G a Sibari, il sindaco di Cassano blocca i lavori. Timori per elettrosmog"},"content":{"rendered":"<p>CASSANO ALLO IONIO(CS) &#8211; Il sindaco di Cassano Ionio ha emesso un&#8217;ordinanza per <strong>bloccare i lavori di realizzazione di un&#8217;a<a title=\"L\u2019antenna 5G spaventa i cittadini: monta la protesta a Sibari\" href=\"https:\/\/quicosenza.it\/news\/16789\" target=\"_blank\" rel=\"noopener\">ntenna 5G<\/a><\/strong> nella frazione Sibari. La decisione, presa per <strong>motivi di ordine pubblico e di pubblica incolumit\u00e0,<\/strong> \u00e8 stata presa da Gianni Papasso alla luce delle proteste degli abitanti e di una riunione svoltasi nella serata di ieri alla presenza dello stesso sindaco.<\/p>\n<p>&#8220;<strong>Sono stato e sono fortemente preoccupato<\/strong> &#8211; ha detto Papasso all&#8217;incontro &#8211; per la realizzazione non soltanto per la questione elettromagnetica ma anche per il danno ambientale e paesaggistico prodotto dall&#8217;installazione di questo <strong>palo alto circa 40 metri nel pieno centro di Sibari<\/strong>. Sono fortemente preoccupato perch\u00e9 all&#8217;assemblea hanno partecipato tantissimi cittadini e ho visto che c&#8217;\u00e8 tantissima tensione che pu\u00f2 sfociare in problemi di ordine e sicurezza pubblica cos\u00ec come sono preoccupato dalle parole di un importante medico che ha affermato a chiare lettere che ci possono essere forti rischi per la salute&#8221;. Stamani, quindi, il sindaco ha emesso l&#8217;ordinanza in modo, \u00e8 scritto in una nota, &#8220;da poter avviare una serie di verifiche medico-sanitario, per vedere se sono state <strong>rispettate le distanze<\/strong> (visto che a pochi metri ci sono due scuole, un oratorio e tante case) ma, soprattutto, per la tutela dell&#8217;ordine e della sicurezza pubblica visto che, al di l\u00e0 della tensione registrata nel corso dell&#8217;assemblea, gi\u00e0 in mattinata alcuni cittadini erano molto agitati&#8221;.<\/p>\n<p>&#8220;Ho espresso sempre contrariet\u00e0 alla realizzazione di questa antenna &#8211; ha ricordato Papasso &#8211; non perch\u00e9 non creda nella modernit\u00e0 e nell&#8217;assicurare i servizi al cittadino. Il problema \u00e8 di altra natura. E lo dimostra il fatto che come amministrazione ci siamo sempre opposti alla realizzazione sia di questa che di altre antenne sul territorio. Abbiamo convocato, nel febbraio 2022, un consiglio comunale e grazie al voto della mia sola maggioranza (l&#8217;opposizione abbandon\u00f2 i lavori) gli uffici comunicarono il diniego alla costruzione alla ditta. Poi, purtroppo, il Tar ha dato loro ragione. Ora, per\u00f2, la situazione cambia perch\u00e9 c&#8217;\u00e8 troppo tumulto, c&#8217;\u00e8 preoccupazione per l&#8217;ordine e la sicurezza pubblica e fortissima preoccupazione per la salute&#8221;.<\/p>\n<p><iframe loading=\"lazy\" title=\"L'antenna 5G spaventa i cittadini di Sibari\" src=\"https:\/\/www.youtube.com\/embed\/yVz0V3Xmgeo\" width=\"850\" height=\"478\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h3>Laghi &#8220;<strong>T<\/strong><b>raliccio antenna 5G a pochi metri da case e scuole&#8221;<\/b><\/h3>\n<p>Contrario all&#8217;antenna anche il \u00a0consigliere regionale,\u00a0<b>Ferdinando Laghi<\/b> &#8220;Da medico sono preoccupato per la salute dei cittadini di Sibari e dei pi\u00f9 piccoli in particolare, che si vedranno a pochi metri dalle loro case e dalla scuola che l\u00ec si trova un&#8217;antenna radio base, le cui radiazioni sono potenzialmente pericolose per la salute di tutti, maggiormente per i bambini che rientrano tra le fasce pi\u00f9 esposte. <strong>La salute \u00e8 un bene prezioso e va difesa<\/strong> con attenzione e rigore da parte delle Istituzioni, ma anche rispettata da chi opera nel settore delle telecomunicazioni. La semplice osservanza dei limiti di legge non rappresenta infatti una garanzia assoluta di innocuit\u00e0 ed \u00e8 perci\u00f2 necessario adottare ogni possibile cautela aggiuntiva&#8221; ha dichiarato il consigliere regionale sulla vicenda che ha visto la cittadinanza di Sibari, frazione di Cassano Jonio, scendere in strada e protestare affinch\u00e9 un<strong> mastodontico traliccio non venga impiantato<\/strong>. A pochi metri da esso, infatti, vi sono non solo alcune abitazioni, ma anche parchi giochi e scuole, discriminante che fa aumentare le preoccupazioni di residenti e genitori degli alunni.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/16790\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-493905\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/01\/Traliccio5G3-711x400.jpeg\" alt=\"Antenna 5G\" width=\"540\" height=\"304\" title=\"\"><\/a><\/p>\n<p>&#8220;Sono tornato a Sibari, dopo essere stato alla Cittadella Regionale a Catanzaro, perch\u00e9 ho voluto partecipare all&#8217;assemblea pubblica indetta dal sindaco Papasso &#8211; continua il consigliere Laghi -, per continuare a seguire la vicenda dell&#8217;antenna e ho, nell&#8217;occasione, dato anche la mia disponibilit\u00e0 per un incontro pubblico per informare sui rischi per la salute legati all&#8217;<strong>esposizione ai campi elettromagnetici<\/strong>&#8220;. Laghi, che per l&#8217;attivit\u00e0 svolta da molti anni nell&#8217;Associazione Internazionale Medici per l&#8217;Ambiente (ISDE) -di cui \u00e8 stato Presidente internazionale ed \u00e8, attualmente, vice-Presidente della sezione italiana &#8211; di queste tematiche ben conosce gli aspetti scientifici, ha dimostrato, oggi come diversi anni fa per una analoga vicenda, la sua vicinanza ai cittadini di Sibari, comprendendone le preoccupazioni e la rabbia&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La decisione, presa per motivi di ordine pubblico e di pubblica incolumit\u00e0. Laghi \u00abmastodontico traliccio dell&#8217;antenna 5G vicino a scuole e case\u00bb<\/p>\n","protected":false},"author":55,"featured_media":183243,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[19],"class_list":["post-183242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=183242"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183242\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183243"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=183242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=183242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=183242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}