{"id":183331,"date":"2023-01-15T13:00:15","date_gmt":"2023-01-15T12:00:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/494147-covid-autorizzato-il-vaccino-pfizer-contro-le-varianti-omicron-ai-bimbi-tra-5-e-11-anni"},"modified":"2023-01-15T13:00:15","modified_gmt":"2023-01-15T12:00:15","slug":"494147-covid-autorizzato-il-vaccino-pfizer-contro-le-varianti-omicron-ai-bimbi-tra-5-e-11-anni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/494147-covid-autorizzato-il-vaccino-pfizer-contro-le-varianti-omicron-ai-bimbi-tra-5-e-11-anni\/","title":{"rendered":"Covid, autorizzato il vaccino Pfizer contro le varianti Omicron ai bimbi tra 5 e 11 anni"},"content":{"rendered":"<p>ROMA &#8211; Il Ministero della Salute ha pubblicato la circolare che recepisce il parere della Commissione Tecnico Scientifica (Cts) dell&#8217;Agenzia del farmaco (Aifa) <strong>con il via libera al vaccino Cominarty di Pfizer contro le varianti Omicron Ba.4 e Ba.5<\/strong> come richiamo per i bambini tra 5 e 11 anni. Il vaccino \u00e8 raccomandato per i bimbi pi\u00f9 fragili<strong> ma su richiesta dei genitori potr\u00e0 essere somministrato a tutti i bambini compresi nella fascia di et\u00e0.<\/strong><\/p>\n<p>La Cts di Aifa, nella seduta del 5 dicembre 2022, accogliendo il parere espresso dall&#8217;Agenzia Europea dei Medicinali (Ema) aveva gi\u00e0 autorizzato la formulazione Original\/Omicron BA.4-5 (5\/5 microgrammi). &#8220;<strong>Si estende la raccomandazione della dose di richiamo ai bambini nella fascia di et\u00e0 5-11 anni (compresi),<\/strong> che presentino condizioni di fragilit\u00e0 tali da esporli allo sviluppo di forme pi\u00f9 severe di infezione da SARS-CoV-2&#8243; si legge nella circolare. &#8220;Inoltre &#8211; si precisa &#8211; tenuto conto dell&#8217;indicazione di utilizzo autorizzata da Ema e Aifa, tale formulazione <strong>potr\u00e0 essere resa disponibile anche per il richiamo dei bambini, nella fascia di et\u00e0 5-11 anni<\/strong> (compresi), che non presentino tali condizioni, su richiesta del genitore o di chi ne ha la potest\u00e0 genitoriale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Ministero della salute pubblica la circolare che raccomanda il vaccino Pfizer soprattutto ai bambini fragili ma possono richiederlo tutti<\/p>\n","protected":false},"author":61,"featured_media":183332,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-183331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=183331"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183331\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183332"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=183331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=183331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=183331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}