{"id":183366,"date":"2023-01-16T11:11:52","date_gmt":"2023-01-16T10:11:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/494308-scissione-amantea-campora-sospeso-il-referendum-del-22-gennaio"},"modified":"2023-01-27T12:00:54","modified_gmt":"2023-01-27T11:00:54","slug":"494308-scissione-amantea-campora-sospeso-il-referendum-del-22-gennaio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/494308-scissione-amantea-campora-sospeso-il-referendum-del-22-gennaio\/","title":{"rendered":"Scissione Amantea-Campora, sospeso il referendum del 22 gennaio"},"content":{"rendered":"<p>AMANTEA (CS) &#8211; Il Consiglio di Stato ha accolto il ricorso presentato dal Comune di Amantea sulla sospensiva del referendum per l\u2019annessione del territorio di Campora al Comune di Serra d\u2019Aiello e di fatto ha bloccato il referendum. Esulta il primo cittadino di Amantea, <strong>Vincenzo Pellegrino<\/strong> che su Facebook ha commentato la decisione: \u201cl\u2019Amministrazione Comunale di Amantea, promotrice del ricorso che ribalta le decisioni del TAR Calabria, (ricordiamo che quest\u2019ultimo per ben due volte si era espresso con il rigetto della stessa istanza) considera la decisione assunta <strong>solo un passaggio<\/strong>, sia pur <strong>importante<\/strong>, del percorso che porter\u00e0 al giudizio di merito&#8221;.<\/p>\n<p>&#8220;Nell\u2019ordinanza &#8211; scrive Pellegrino &#8211; lo stesso Consiglio ritiene, a fronte della rilevanza degli effetti per il Comune di Amantea e alla luce degli elementi rappresentati dalle parti, <strong>non sussitenti situazioni di urgenza<\/strong> che impongano lo svolgimento del referendum consultivo anteriormente alla decisione di merito \u201cin cui &#8211; si afferma tra l\u2019altro nel pronunciamento &#8211; vanno necessariamente affrontate, per la loro complessit\u00e0, le questioni poste dai motivi di ricorso. Considerato altres\u00ec che le questioni sottese non appaiono manifestamente infondate, bens\u00ec meritevoli di adeguata considerazione e approfondimento nella sede propria di merito\u201d. Per il momento dunque, il referendum \u00e8 sospeso.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Consiglio di Stato ha accolto l\u2019istanza di sospensione cautelare del referendum sulla riperimetrazione del territorio di Serra d\u2019Aiello con l\u2019annessione di Campora San Giovanni<\/p>\n","protected":false},"author":42,"featured_media":183367,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-183366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=183366"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183366\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183367"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=183366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=183366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=183366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}