{"id":183731,"date":"2023-01-23T15:20:09","date_gmt":"2023-01-23T14:20:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/495430-a-lorica-si-torna-a-sciare-dopo-la-messa-in-sicurezza-riaprono-le-piste"},"modified":"2023-01-23T15:20:09","modified_gmt":"2023-01-23T14:20:09","slug":"495430-a-lorica-si-torna-a-sciare-dopo-la-messa-in-sicurezza-riaprono-le-piste","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/495430-a-lorica-si-torna-a-sciare-dopo-la-messa-in-sicurezza-riaprono-le-piste\/","title":{"rendered":"Sila, a Lorica si torna a sciare: dopo la messa in sicurezza riaprono le piste"},"content":{"rendered":"<p>COSENZA &#8211; Si sono conclusi i lavori di battitura e <strong>messa in sicurezza della Pista di Rientro e di quella del Cavaliere<\/strong>, che da domani potranno accogliere tutti gli amanti dello sci. <strong>Gli impianti di risalita<\/strong>, gi\u00e0 in funzione dallo scorso 10 dicembre,<strong> saranno aperti tutti i giorni dalle 9 alle 16.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si sono conclusi i lavori di battitura e messa in sicurezza della Pista di Rientro e di quella del Cavaliere che riaprono da domani<\/p>\n","protected":false},"author":58,"featured_media":183732,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-183731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=183731"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183732"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=183731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=183731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=183731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}