{"id":183735,"date":"2023-01-23T16:02:43","date_gmt":"2023-01-23T15:02:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/495442-incidente-stradale-sulla-ss106-nel-cosentino-3-feriti-interviene-lelisoccorso"},"modified":"2023-01-23T16:02:43","modified_gmt":"2023-01-23T15:02:43","slug":"495442-incidente-stradale-sulla-ss106-nel-cosentino-3-feriti-interviene-lelisoccorso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/495442-incidente-stradale-sulla-ss106-nel-cosentino-3-feriti-interviene-lelisoccorso\/","title":{"rendered":"Incidente stradale sulla SS106 nel cosentino, 3 feriti: interviene l&#8217;elisoccorso"},"content":{"rendered":"<p>CASSANO ALLO IONIO (CS) &#8211; Incidente lungo<strong> la strada statale 106 Radd &#8220;Jonica&#8221;. Il tratto <\/strong>\u00e8 provvisoriamente chiuso al transito, in entrambe le direzioni<strong> nel territorio comunale di Cassano allo Jonio, a causa del sinistro<\/strong> .<\/p>\n<p>Per consentire<strong> l&#8217;atterraggio dell&#8217;elisoccorso, \u00e8 provvisoriamente chiuso anche il tratto stradale della SS534 &#8216;Di Cammarata e Degli Stombi&#8217;<\/strong>. Per cause in corso di accertamento, il sinistro ha coinvolto<strong> un mezzo pesante ed un veicolo leggero, provocando il ferimento di tre persone.<\/strong> Sul posto \u00e8 presente il personale delle Forze dell&#8217;Ordine, di Anas, del 118 e dei Vigili del Fuoco impegnati nei rilievi del caso e nella gestione della viabilit\u00e0, allo scopo di ripristinare la regolare circolazione il prima possibile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sinistro ha coinvolto un mezzo pesante ed un veicolo leggero. Per consentire l&#8217;atterraggio dell&#8217;elisoccorso \u00e8 stato chiuso il tratto stradale<\/p>\n","protected":false},"author":61,"featured_media":183736,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-183735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=183735"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183736"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=183735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=183735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=183735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}