{"id":183737,"date":"2023-01-23T16:52:29","date_gmt":"2023-01-23T15:52:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/495457-mezzo-pesante-si-ribalta-su-a2-chiuso-il-tratto-tra-lauria-e-lagonegro"},"modified":"2023-01-23T16:52:29","modified_gmt":"2023-01-23T15:52:29","slug":"495457-mezzo-pesante-si-ribalta-su-a2-chiuso-il-tratto-tra-lauria-e-lagonegro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/495457-mezzo-pesante-si-ribalta-su-a2-chiuso-il-tratto-tra-lauria-e-lagonegro\/","title":{"rendered":"Mezzo pesante si ribalta su A2: chiuso il tratto tra Lauria e Lagonegro"},"content":{"rendered":"<p class=\"v1x_western\">COSENZA &#8211; <strong>A causa di un mezzo pesante ribaltato, \u00e8 provvisoriamente chiuso un tratto della A2 &#8216;Autostrada del Mediterraneo- in direzione Fisciano &#8211; tra gli svincoli di Lauria nord e Lagonegro sud<\/strong>, in provincia di Potenza. Per consentire le operazioni di rimozione del mezzo, al momento il <strong>traffico veicolare viene deviato<\/strong>, per i soli veicoli leggeri, all&#8217;uscita dallo svincolo di Lauria nord (km 140,900) con proseguimento <strong>lungo la statale 19 &#8216;Delle Calabrie&#8217; e la SS 25<\/strong>, con ingresso in A2 presso lo svincolo di Lagonegro nord (km 127,513). Sul posto sono presenti le squadre Anas e le Forze dell&#8217;Ordine per la gestione del traffico e per consentire il totale ripristino della viabilit\u00e0 nel pi\u00f9 breve tempo possibile.<\/p>\n<p class=\"v1MsoNormal\"><strong><span style=\"color: #ff0000;\">++++AGGIORNAMENTO ORE 19:20+++<\/span><\/strong><\/p>\n<p class=\"v1MsoNormal\"><b>RIAPERTA A2 &#8216;AUTOSTRADA DEL MEDITERRANEO&#8217;, TRA LAURIA E LAGONEGRO, IN PROVINCIA DI POTENZA<\/b><\/p>\n<p class=\"v1x_western\"><span class=\"v1x_ContentPasted1\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sul posto sono presenti le squadre Anas e le\u00a0Forze dell&#8217;Ordine per la gestione del traffico e per consentire il\u00a0ripristino della viabilit\u00e0 nel pi\u00f9 breve tempo possibile<\/p>\n","protected":false},"author":58,"featured_media":183738,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-183737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=183737"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/183737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/183738"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=183737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=183737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=183737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}