{"id":184313,"date":"2023-01-27T05:30:13","date_gmt":"2023-01-27T04:30:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/495407-airc-tornano-in-piazza-le-arance-della-salute-per-la-ricerca-contro-il-cancro"},"modified":"2023-01-27T05:30:13","modified_gmt":"2023-01-27T04:30:13","slug":"495407-airc-tornano-in-piazza-le-arance-della-salute-per-la-ricerca-contro-il-cancro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/495407-airc-tornano-in-piazza-le-arance-della-salute-per-la-ricerca-contro-il-cancro\/","title":{"rendered":"Airc, tornano in piazza &#8220;Le Arance della Salute&#8221; per la ricerca contro il cancro"},"content":{"rendered":"<p>ROMA &#8211; Tornano in piazza &#8220;Le Arance della Salute&#8221;, la raccolta fondi della Fondazione Airc per promuovere la ricerca sui tumori. <a href=\"https:\/\/quicosenza.it\/news\/16876\">Sabato 28 gennaio nelle piazze italiane<\/a>, i volontari distribuiranno <strong>arance, miele e marmellata<\/strong>. Grazie alle iniziative di raccolta fondi come questa, <strong>Airc nel 2023 investir\u00e0 137 milioni per sostenere circa 6 mila ricercatori, 704 progetti di ricerca, 91 borse di studio e 21 programmi speciali<\/strong>, per rendere il <strong>cancro sempre pi\u00f9 curabile<\/strong>.<\/p>\n<h3>14mila casi di tumore in pi\u00f9 rispetto al 2020<\/h3>\n<p>Mentre la campagna <strong>&#8216;La salute nelle nostre mani&#8217;<\/strong> porter\u00e0 la prevenzione nelle <strong>scuole<\/strong>, nei <strong>bar<\/strong> e nei <strong>supermercati<\/strong>. Lo scorso anno in Italia sono stati stimati <strong>390.700 nuovi casi di tumore<\/strong>, <strong>14.100<\/strong> in pi\u00f9 rispetto al 2020. Una ripresa che rischia di peggiorare se non si riducono stili di vita non salutari: il 33% degli adulti \u00e8 in sovrappeso e il 10% obeso, il 24% fuma e i sedentari sono aumentati dal 23% nel 2008 al 31% nel 2021.<\/p>\n<p>Lo slogan della campagna &#8216;La salute nelle nostre mani&#8217; sintetizza l&#8217;impegno di Airc per sensibilizzare i cittadini sull&#8217;importanza di compiere gesti concreti per la nostra salute. &#8220;Abitudini e comportamenti pi\u00f9 salutari potrebbero evitare la comparsa di circa un tumore su tre &#8211; ricorda Federico Caligaris Cappio, direttore scientifico di Fondazione Airc. &#8211; Per questo, un &#8216;decalogo della salute&#8217;, stilato dal Fondo mondiale per la ricerca sul cancro sar\u00e0 distribuito insieme ai prodotti solidali nella sacca che include anche ricette a tema arancia firmate da Benedetta Parodi.<\/p>\n<p><strong>Oggi e domani, sabato 28 gennaio le Arance entrano in oltre 1.000 scuole coinvolgendo studenti, genitori e insegnanti con l&#8217;iniziativa &#8220;Cancro, io ti boccio&#8221;.<\/strong><\/p>\n<p>Dal <strong>4 febbraio<\/strong>, in occasione del <strong>World Cancer Day<\/strong>, l&#8217;appuntamento con la salute sar\u00e0 in pi\u00f9 di 9.000 supermercati di oltre 50 insegne: per ogni reticella di &#8220;Arance rosse per la ricerca&#8221; i punti vendita aderenti doneranno 50 centesimi ad Airc. Sempre dal 4 febbraio, grazie alla collaborazione con la Confederazione Nazionale dell&#8217;Artigianato e della Piccola e Media Impresa (Cna), bar e ristoranti aderenti doneranno ad AIRC 50 centesimi per ogni spremuta di arance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Due iniziative per aiutare l&#8217;Airc nella ricerca. Oltre alle Arance dell&#8217;Airc anche &#8216;La salute nelle nostre mani&#8217; per portare la prevenzione nelle scuole, nei bar e nei supermercati<\/p>\n","protected":false},"author":42,"featured_media":184314,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-184313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/184313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=184313"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/184313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/184314"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=184313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=184313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=184313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}