{"id":184453,"date":"2023-01-29T08:00:59","date_gmt":"2023-01-29T07:00:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/495971-alloggi-universitari-e-fondi-sperperati-nasce-il-coordinamento-praxis-allunical"},"modified":"2023-01-29T08:00:59","modified_gmt":"2023-01-29T07:00:59","slug":"495971-alloggi-universitari-e-fondi-sperperati-nasce-il-coordinamento-praxis-allunical","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/495971-alloggi-universitari-e-fondi-sperperati-nasce-il-coordinamento-praxis-allunical\/","title":{"rendered":"Alloggi universitari e fondi sperperati, nasce il coordinamento Praxis all&#8217;Unical"},"content":{"rendered":"<p>RENDE &#8211;\u00a0 Nato a seguito delle proteste che hanno investito il centro residenziale a causa dei fondi sperperati per il residence <strong>Rocchi<\/strong>, abbandonato e mai utilizzato, e per la <strong>carenza di alloggi messi a disposizione dall&#8217;Ateneo<\/strong>, insufficienti rispetto alla domanda degli\/delle studenti, il nuovo coordinamento universitario Praxis \u00e8 pronto a presentarsi con il suo <strong>programma politico.\u00a0<\/strong>Il coordinamento di studenti che sara presentato luned\u00ec alle 18, porta all&#8217;attenzione diversi punti e rivendicazioni tra cui:<\/p>\n<p>&#8211; <strong>L&#8217;opposizione alle logiche aziendalistiche<\/strong> che imperano nelle universit\u00e0 italiane. &#8220;Ad oggi l&#8217;universit\u00e0 della calabria risulta essere un&#8217;oasi nel deserto, un laureificio che non tiene conto dei bisogni reali e della formazione a 360 gradi della comunit\u00e0 studentesca, ma guarda solo agli standard di produttivit\u00e0 interna&#8221; .<\/p>\n<p>&#8211; <strong>Il diritto alla salute nel campus<\/strong>. Il centro sanitario &#8211; dicono- risulta essere fantasma e non vi \u00e8 alcuna sicurezza per studenti fuori sede e non. Tanto l&#8217;Asp quanto i vertici dell&#8217;ateneo si disinteressano completamente alla questione e ci\u00f2 si vede dal consultorio e dall&#8217;unit\u00e0 di continuit\u00e0 assistenziale che, non rientrando nei meccanismi del profitto, vengono indicati come presidi sanitari dell&#8217;unical ma di fatto sono scatole vuote alle quali non ci si pu\u00f2 rivolgere. Le studentesse, in particolare, sono private di servizi essenziali come quello consultoriale e spesso non si hanno mezzi e modi per recarsi al di fuori del campus. In pi\u00f9 l&#8217;ateneo \u00e8 completamente sordo rispetto ai temi quali la sessualit\u00e0 e il genere.<\/p>\n<p>&#8211; <strong>Sussidi<\/strong> per acquisto di materiale didattico e potenziamento del trasporto pubblico affinch\u00e9 si possa creare una connessione reale tra l&#8217;universit\u00e0 e l&#8217;area urbana, senza che l\u0259 studenti si vedano costrett\u0259 a non poter uscire dal campus e a non poter partecipare agevolmente alle lezioni.<\/p>\n<p>&#8211; <strong>Accessibilit\u00e0, infrastrutturale e didattica<\/strong>. Vogliamo un campus realmente inclusivo. Supporto e programmi ad hoc per studenti con disabilit\u00e0 psicomotorie. E in particolare la mole di studenti internazionali, uno dei grandi vanti dell&#8217;ateneo, gode di una pessima accoglienza e nessun supporto all&#8217;integrazione sia nel campus in s\u00e9 che rispetto al programma didattico. Il supporto linguistico e l&#8217;orientamento sono rilegati alla volont\u00e0 dei singoli docenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sar\u00e0 presentato luned\u00ec 31 gennaio alle 18, nell&#8217;Aula Giulio Regeni dell&#8217;Unical, il coordinamento universitario Praxis<\/p>\n","protected":false},"author":42,"featured_media":184454,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[19],"class_list":["post-184453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/184453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=184453"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/184453\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/184454"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=184453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=184453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=184453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}