{"id":184551,"date":"2023-01-30T06:07:44","date_gmt":"2023-01-30T05:07:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/496325-tragedia-a-cetraro-42enne-investito-sulla-statale-18-muore-in-ospedale"},"modified":"2023-01-31T16:11:27","modified_gmt":"2023-01-31T15:11:27","slug":"496325-tragedia-a-cetraro-42enne-investito-sulla-statale-18-muore-in-ospedale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/496325-tragedia-a-cetraro-42enne-investito-sulla-statale-18-muore-in-ospedale\/","title":{"rendered":"Tragedia a Cetraro: 42enne investito sulla Statale 18, muore in ospedale"},"content":{"rendered":"<p>CETRARO (CS) &#8211; Un uomo di 42 anni <strong>Pietro Ferrante<\/strong>, \u00e8 morto ieri sera a <strong>Cetraro<\/strong> dopo essere stato investito da un\u2019auto sulla Statale 18 Tirrenica, a pochi metri di distanza da un ristorante. Secondo quanto emerso Ferrante stava attraversando la strada quando l&#8217;auto l&#8217;ha centrato in pieno. Il conducente si \u00e8 fermato a prestare soccorso e poco dopo sono arrivati i sanitari del 118.<\/p>\n<p>Trasportato con urgenza in gravi condizioni all&#8217;ospedale a Cetraro, il 42enne \u00e8 deceduto. Al vaglio dei carabinieri la ricostruzione della dinamica dell\u2019incidente. Sui social numerosi i messaggi di cordoglio: &#8220;Oggi Cetraro perde una grande persona, un ragazzo, molti di noi perdono un grande amico, una rockstar di quelle vere&#8221;. Amante della musica, gli amici lo definiscono &#8220;una delle persone pi\u00f9 buone d&#8217;animo mai conosciute&#8221;. Un ragazzo allegro, sincero. &#8220;Oggi tutti ti piangono perch\u00e9 tutti hanno perso un amico, quell&#8217;amico che solo tu sapevi essere&#8221;.<\/p>\n<h3>Il cordoglio del sindaco, Ermanno Cennamo<\/h3>\n<p>&#8220;Stamattina la nostra comunit\u00e0 si \u00e8 svegliata incredula, sopraffatta dalla pi\u00f9 tragica delle notizie, la perdita di un nostro giovane concittadino, Pietro&#8221;. Il primo cittadino di Cetraro, Cennamo, ha espresso con un post su Facebook, &#8220;unitamente all&#8217;amministrazione comunale e alla cittadinanza intera, <strong>profondo cordoglio e vicinanza ai familiari del giovane Pietro,<\/strong> prematuramente strappato alla vita per un tragico incidente&#8221;.<\/p>\n<p>&#8220;Una notizia cos\u00ec dolorosa ci getta sempre nello sconforto, ancor di pi\u00f9 quando si apprende che a perdere la vita \u00e8 un giovane ragazzo che aveva ancora tanti sogni da realizzare, speranze e progetti, la vita ancora tutta da prendere a morsi, traguardi da raggiungere e gioie da condividere con le persone care. Oggi abbiamo perso tutti qualcosa, la famiglia, gli amici, tutti quelli che gli hanno voluto bene ma anche chi, almeno una volta, ha incrociato il suo dolce sorriso per la strada. Oggi ci sentiamo tutti un po&#8217; pi\u00f9 soli&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; accaduto intorno alle 19 ieri sera. L&#8217;uomo \u00e8 deceduto nonostante la corsa all&#8217;ospedale di Cetraro. Dolore e sgomento sui social<\/p>\n","protected":false},"author":42,"featured_media":184552,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-184551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/184551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=184551"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/184551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/184552"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=184551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=184551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=184551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}