{"id":185698,"date":"2023-02-04T16:06:03","date_gmt":"2023-02-04T15:06:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=185698"},"modified":"2023-04-06T10:43:12","modified_gmt":"2023-04-06T08:43:12","slug":"cosenza-ternana-finisce-senza-reti-i-rossoblu-restano-ultimi-esordio-per-zarate","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-ternana-finisce-senza-reti-i-rossoblu-restano-ultimi-esordio-per-zarate\/","title":{"rendered":"Cosenza-Ternana finisce senza reti, i rossoblu restano ultimi. Esordio per Zarate"},"content":{"rendered":"<p>COSENZA &#8211;\u00a0Ieri, durante la <a href=\"https:\/\/quicosenza.it\/news\/sport\/da-zarate-a-marras-il-cosenza-presenta-i-nuovi-acquisti-uniti-per-centrare-la-salvezza\" target=\"_blank\" rel=\"noopener\">presentazione<\/a> dei nuovi arrivati, Gemmi e Viali erano stati chiari: <strong>Cosenza-Ternana \u00e8 sfida cruciale<\/strong> per dare continuit\u00e0 alla vittoria con il Parma. Ma il match contro gli umbri, che ha visto nuovamente l<strong>&#8216;assenza degli ultras dalle due curve del Marulla<\/strong>, non ha portato la vittoria auspicata.<\/p>\n<p>Nonostante la buona volont\u00e0<strong> i rossoblu,<\/strong> che hanno messo in campo comunque tanta determinazione ma anche molta confusione nel finale, non hanno trovato la via della rete, anche con l&#8217;apporto di <strong>Mauro Zarate<\/strong> entrato negli ultimi 20&#8242; minuti.<\/p>\n<p>Cosenza Ternana finisce senza reti, con <strong>un palo a testa<\/strong> (Vaisanen per i rossoblu e Favilli per gli umbri) nella ripresa, una <strong>conclusione di Nasti<\/strong> nel primo tempo respinta da Iannarilli e una <strong>bella parata di Micai sulla girata di Defendi<\/strong> nella ripresa. <strong>E con i risultati delle dirette concorrenti<\/strong>, il Cosenza resta inchiodato all&#8217;ultimo posto in classifica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-185705 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana2.jpg\" alt=\"Cosenza Ternana\" width=\"515\" height=\"356\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana2.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana2-300x207.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana2-768x530.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana2-150x104.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana2-218x150.jpg 218w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana2-696x481.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana2-608x420.jpg 608w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana2-100x70.jpg 100w\" sizes=\"auto, (max-width: 515px) 100vw, 515px\" \/><\/p>\n<h3>Cosenza-Ternana a viso aperto<\/h3>\n<p>Come accaduto contro il Parma il Cosenza parte subito forte e, dopo 2&#8242; minuti, si rende gi\u00e0 pericoloso. <strong>Uno due Rispoli-Marras<\/strong> sull&#8217;out di destra e conclusione del terzino che spedisce alto da buona posizione. L&#8217;ex Bari, invece, si mette in proprio al 4&#8242; e ci prova con un <strong>sinistro a giro da limite<\/strong> che non ha miglior sorte. La Ternana replica un minuto dopo con un <strong>colpo di testa di Diakite <\/strong>che termina alto sulla traversa.<\/p>\n<p>Il francese al minuto 8&#8242; con un<strong> velenoso tiro-cross<\/strong> chiama Micai alla deviazione in angolo. Ben pi\u00f9 impegnativa la parata del portiere del Cosenza sulla conclusione dalla distanza di Sorensen. La Ternana sale di giri e mette pressione ai rossoblu costretti a lunghi lanci per smarcare i tre attaccanti. <strong>Al 22&#8242; si rivede il Cosenza<\/strong>: Nasti controlla un bel pallone a centrocampo, serve Marras che verticalizza subito per Finotto.<\/p>\n<p>L&#8217;attaccante arriva al limite e conclude sul primo palo di destro. Pallone che termina al lato. Il Cosenza capisce allora che deve giocare di rimessa anche se <strong>al 28&#8242; rischia di finire sotto<\/strong>. Partipilo raccoglie un pallone sporco e calcia in diagonale: pallone che esce di un nulla alla destra di Micai. Al 31&#8242; Voca si accascia al suolo per un problema muscolare. Al suo posto entra Praszelik. <strong>Proprio il centrocampista polacco da il via all&#8217;azione pi\u00f9 pericolosa del Cosenza<\/strong> in tutto il primo tempo. Sfondamento centralmente in area, pallone finisce sui piedi di Nasti che calcia in diagonale chiamando alla risposta Iannarilli. Dopo 2&#8242; di recupero si va al riposo sullo zero a zero.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-185707 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana5.jpg\" alt=\"Cosenza Ternana\" width=\"536\" height=\"357\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana5.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana5-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana5-768x511.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana5-150x100.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana5-696x464.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana5-631x420.jpg 631w\" sizes=\"auto, (max-width: 536px) 100vw, 536px\" \/><\/p>\n<h3>Palo di Vaisanen, legno anche di Favilli<\/h3>\n<p>La ripresa si apre senza cambi e con il Cosenza subito vicino al goal. Prima <strong>Rigione trova l&#8217;opposizione della difesa<\/strong>. Poi, sul primo corner della gara, pallone rimesso in area per la <strong>testa di Vaisanen che anticipa tutti ma colpisce il palo<\/strong>. Sul proseguo dell&#8217;azione Cal\u00f2 non riesce a trovare il guizzo vincente e la difesa della ternana libera. Entrano La Vardera e Delic per D&#8217;Orazio e Finotto.<\/p>\n<p>Al 68&#8242; nuovo corner battuto da Cal\u00f2 e <strong>nuova inzuccata di Vaisanen<\/strong>. Pallone per\u00f2 centrale che finisce la tra mani di Iannarilli. <strong>Cal\u00f2 ci prova su punizione<\/strong> ma il suo destro a giro finisce alto.<strong> Al 70&#8242; arriva l&#8217;esodio di Mauro Zarate<\/strong> con la maglia del Cosenza. Con lui entra anche Agostinelli che rileva Cal\u00f2. Ma <strong>\u00e8 la Ternana, con il Cosenza all&#8217;attacco ad aver due grandissime occasioni<\/strong>.<\/p>\n<p>La prima al minuto 83&#8242; con una girata sotto porta di Defendi respinta da Micai. La seconda, la pi\u00f9 clamorosa, con un <strong>colpo di testa di Favilli che colpisce il palo interno<\/strong>. Il Cosenza sembra sulle gambe e la Ternana prova ad approfittarne. I rossoblu resistono e dopo 5&#8242; di recupero arriva il triplice fischio finale. Ora per il Cosenza la difficile trasferta di Bari.<\/p>\n<p>\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014-\u2014\u2014-\u2014\u2014-\u2014\u2014-\u2014\u2014-<\/p>\n<div class=\"mvp-post-soc-in\">\n<div id=\"mvp-content-body\" class=\"left relative\">\n<div id=\"mvp-content-body-top\" class=\"left relative\">\n<div id=\"mvp-content-main\" class=\"left relative\">\n<div id=\"tps_slideContainer_494156\" class=\"theiaPostSlider_slides\">\n<div class=\"theiaPostSlider_preloadedSlide\">\n<p><strong>COSENZA CALCIO (4-3-1-2):<\/strong> Micai; Rispoli, Rigione, Vaisanen, D\u2019Orazio (61&#8242; La Vardera); Brescianini, Voca (31&#8242; Praszelik), Cal\u00f2 (70&#8242; Agostinelli); Marras; Nasti (70&#8242; Zarate), Finotto (61&#8242; Delic)<br \/>\n<strong>Panchina:<\/strong> Marson, Zarate, D&#8217;Urso, Meroni, Salihamidzic, Praszelik, Agostinelli, Delic, Venturi, Martino, La Vardera, Prestianni<br \/>\n<strong>Allenatore:<\/strong>\u00a0Wiliam Viali<\/p>\n<p><strong>TERNANA CALCIO (3-4-2-1):<\/strong> Iannarilli; Diakit\u00e8, Sorensen, Mantovani; Ghiringhelli (70&#8242; Cassata), Agazzi, Di Tacchio, Corrado (70&#8242; Martella); Coulibaly (70&#8242; Defendi), Partipilo (82&#8242; Falletti); Favilli<br \/>\n<strong>Panchina:<\/strong> Krapikas, Vitali, Mazzarani, Capanni, Proietti, Donnarumma, Falletti, Paghera, Defendi, Bogdan, Cassata, Martella<br \/>\n<strong>Allenatore:<\/strong> Aurelio Andreazzoli<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Arbitro:<\/strong> Signor Lorenzo Maggioni di Lecco<br \/>\n<strong>Assistenti:<\/strong> Signori Luigi Rossi di Rovigo\u00a0 ed Edoardo Raspolini di Livorno<br \/>\n<strong>IV Uomo:<\/strong> Signor Giorgio Di Cicco di Lanciano<br \/>\n<strong>SALA VAR:<\/strong> Signori Davide Ghersini di Genova e Orlando Pagnotta di Nocera Inferiore<\/p>\n<p><strong>Ammoniti: <\/strong>Ghiringhelli (T), D&#8217;Orazio (C)<br \/>\n<strong>Espulsi:\u00a0<\/strong><\/p>\n<p><strong>Angoli: <\/strong>7-5<br \/>\n<strong>Recupero: <\/strong>2&#8242; p.t. &#8211; 5&#8242; s.t.<\/p>\n<p><strong>Note:<\/strong> Pomeriggio nuvoloso ma non freddo a Cosenza, con una temperatura di circa 14 gradi. Terreno del Marulla non in perfette condizioni. Presenti poco pi\u00f9 di 3mila spettatori compresi una cinquantina di tifosi della Ternana.<\/p>\n<p><strong><span style=\"color: blue;\">Foto Cosenza Ternana a cura di Francesco Donato <a href=\"https:\/\/www.fotosportive.it\/2023\/02\/04\/serie-b-2022-2023-23-giornata-cosenza-ternana-0-0-fotogallery\/\" rel=\"noopener\">(QUI tutte le foto)<\/a><\/span><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-185704 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana1.jpg\" alt=\"Cosenza Ternana\" width=\"527\" height=\"342\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana1.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana1-300x195.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana1-768x499.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana1-150x97.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana1-696x452.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana1-647x420.jpg 647w\" sizes=\"auto, (max-width: 527px) 100vw, 527px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-185708 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana4.jpg\" alt=\"Cosenza Ternana\" width=\"542\" height=\"365\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana4.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana4-300x202.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana4-768x517.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana4-150x101.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana4-696x469.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana4-624x420.jpg 624w\" sizes=\"auto, (max-width: 542px) 100vw, 542px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-185709 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana3.jpg\" alt=\"Cosenza Ternana\" width=\"535\" height=\"360\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana3.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana3-300x202.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana3-768x517.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana3-150x101.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana3-696x469.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Cosenza-Ternana3-624x420.jpg 624w\" sizes=\"auto, (max-width: 535px) 100vw, 535px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-185718 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Mauro-Zarate-Cosenza-Ternana.jpg\" alt=\"Mauro Zarate Cosenza Ternana\" width=\"525\" height=\"357\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Mauro-Zarate-Cosenza-Ternana.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Mauro-Zarate-Cosenza-Ternana-300x204.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Mauro-Zarate-Cosenza-Ternana-768x523.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Mauro-Zarate-Cosenza-Ternana-150x102.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Mauro-Zarate-Cosenza-Ternana-696x474.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/Mauro-Zarate-Cosenza-Ternana-617x420.jpg 617w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Cosenza non riesce a bissare il successo contro il Parma e con la Ternana arriva un pareggio senza reti. Palo colpito da Vaisanen e da Favilli<\/p>\n","protected":false},"author":23,"featured_media":185704,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19],"class_list":["post-185698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/185698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=185698"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/185698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/185704"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=185698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=185698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=185698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}