{"id":186062,"date":"2023-02-09T11:10:09","date_gmt":"2023-02-09T10:10:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=186062"},"modified":"2023-02-09T11:10:09","modified_gmt":"2023-02-09T10:10:09","slug":"giochi-e-scommesse-online-sequestrati-beni-per-500mila-euro-ad-un-imprenditore","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/giochi-e-scommesse-online-sequestrati-beni-per-500mila-euro-ad-un-imprenditore\/","title":{"rendered":"Giochi e scommesse online, sequestrati beni per 500mila euro ad un imprenditore"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Compendi aziendali e 15 terreni per un valore che supera i 500mila euro sono stati sequestrati dalla Guardia di finanza ad un imprenditore di Gioia Tauro, con radicati interessi nel centro Italia nel settore dei <strong>giochi e delle scommesse<\/strong>. La figura criminale dell\u2019imprenditore era emersa nell\u2019ambito dell\u2019operazione \u201c<strong>Galassia<\/strong>\u201d che aveva portato alla luce un sofisticato ed altamente <strong>remunerativo sistema criminale<\/strong>, finalizzato <strong>all&#8217;illecita raccolta di scommesse on-line<\/strong> attraverso importanti <strong>bookmakers esteri <\/strong>con sede in Austria e Malta, che avrebbero operato in patto sinallagmatico con la &#8216;ndrangheta.<\/p>\n<h3>Il ruolo dell&#8217;imprenditore<\/h3>\n<p>Avrebbe svolto il ruolo di promotore ed organizzatore di un\u2019associazione inserita nel descritto sistema illecito, e per questo \u00e8 stato rinviato a giudizio per <strong>associazione per delinquere aggravata dal metodo mafioso<\/strong>. A seguito di mirate indagini anche di carattere economico\/patrimoniale, \u00e8 stato sottoposto a sequestro nel mese di giugno 2021, su provvedimento della Sezione Misure di Prevenzione del Tribunale di Reggio Calabria, il patrimonio riconducibile all&#8217;imprenditore.<\/p>\n<p>Successivamente a tale attivit\u00e0, il monitoraggio investigativo ha permesso di rilevare come il <strong>soggetto,<\/strong> <strong>avrebbe continuato ad operare nel settore dei giochi<\/strong>, rigenerandosi dal punto di vista imprenditoriale attraverso la <strong>costituzione di nuove entit\u00e0 giuridiche<\/strong> nella formale titolarit\u00e0 dei suoi prossimi congiunti.<\/p>\n<p>Cos\u00ec facendo, attraverso un complesso sistema di <strong>ramificazioni societarie<\/strong>, ha continuato ad intrattenere rapporti commerciali (traendone profitti) con le societ\u00e0 a lui riconducibili, ricadute nel vincolo del precedente sequestro. Gli accertamenti, inoltre, hanno consentito di rilevare come l\u2019imprenditore, senza disporre di idonee lecite risorse finanziarie, abbia effettuato <strong>rilevanti acquisizioni immobiliari<\/strong>.<\/p>\n<p>Il sequestro ha riguardato il compendio aziendale di 2 ditte individuali e 2 societ\u00e0, tutte operanti nel <strong>settore della gestione e manutenzione degli apparecchi da gioco,<\/strong> nonch\u00e9 di 15 terreni, per un valore complessivamente stimato di oltre 500mila euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Compendi aziendali e 15 terreni per un valore che supera i 500mila euro sono stati sequestrati dalla Guardia di finanza ad un imprenditore di Gioia Tauro, con radicati interessi nel centro Italia nel settore dei giochi e delle scommesse. La figura criminale dell\u2019imprenditore era emersa nell\u2019ambito dell\u2019operazione \u201cGalassia\u201d che aveva portato alla [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":178425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-186062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/186062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=186062"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/186062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/178425"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=186062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=186062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=186062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}