{"id":186574,"date":"2023-02-17T06:30:27","date_gmt":"2023-02-17T05:30:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=186574"},"modified":"2023-02-16T11:22:56","modified_gmt":"2023-02-16T10:22:56","slug":"il-caciocavallo-silano-dop-tra-i-formaggi-piu-apprezzati-al-mondo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/il-caciocavallo-silano-dop-tra-i-formaggi-piu-apprezzati-al-mondo\/","title":{"rendered":"Il Caciocavallo silano DOP tra i formaggi pi\u00f9 apprezzati al mondo"},"content":{"rendered":"<p>COSENZA &#8211; Il dato \u00e8 emerso dalla classifica di <a href=\"https:\/\/www.tasteatlas.com\/50-best-rated-cheeses-in-europe\" rel=\"noopener\">TasteAtlas<\/a> che ha raccolto i migliori formaggi su <strong>scala mondiale<\/strong>. Nei top 50, precisamente al <strong>42\u00b0 posto<\/strong>, si posiziona il <strong>Caciocavallo<\/strong> silano DOP. Il particolare gusto deciso del <strong>Caciocavallo silano DOP conquista tutti i palati<\/strong>: versatile e buono, \u00e8 adatto per l&#8217;alimentazione di grandi e piccini. Una conferma, questa, che spiega come il Caciocavallo Silano Dop sia riuscito a conquistare e rientrare nei primi <strong>50 posti dell&#8217;importante classifica a livello internazionale.<\/strong><\/p>\n<p>Ne va fiero anche il <strong>Ministro dell&#8217;Agricoltura e della Sovranit\u00e0 alimentare, Francesco Lollobrigida<\/strong>, che ha pubblicato la classifica proprio sui suoi canali social ufficiali evidenziando come l&#8217;Italia sia sempre il Paese capofila in fatto di eccellenze enogastronomiche.<\/p>\n<p>E di eccellenze si tratta anche nel caso del Caciocavallo silano DOP che ha decisamente superato i confini nazionali conquistando, oltre che l&#8217;Italia, i palati di tutto il mondo.<\/p>\n<p>&#8220;E&#8217; una vera <strong>soddisfazione per tutto il Consorzio<\/strong> rientrare tra i formaggi pi\u00f9 apprezzati al mondo &#8211; ha dichiarato il presidente Vito Pace &#8211; Il sapore del nostro Caciocavallo silano DOP \u00e8 riuscito a piazzarsi tra i primi 50 prodotti a livello internazionale, un risultato che non pu\u00f2 che significare una grande vittoria per l&#8217;intera filiera. Nonostante si tratti di un risvolto significativo, non ci fermeremo qui. Continueremo a lavorare per la promozione e la qualit\u00e0 dei nostri prodotti per farci apprezzare sempre di pi\u00f9 in contesti nazionali e internazionali&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il dato \u00e8 emerso dalla classifica di TasteAtlas che ha raccolto i migliori formaggi su scala mondiale. Nei top 50, precisamente al 42\u00b0 posto, si posiziona il Caciocavallo silano DOP. Il particolare gusto deciso del Caciocavallo silano DOP conquista tutti i palati: versatile e buono, \u00e8 adatto per l&#8217;alimentazione di grandi e piccini. [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":186576,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-186574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/186574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=186574"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/186574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/186576"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=186574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=186574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=186574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}