{"id":18681,"date":"2013-03-01T12:49:25","date_gmt":"2013-03-01T11:49:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=18681"},"modified":"2023-01-17T13:16:38","modified_gmt":"2023-01-17T12:16:38","slug":"6831-in-giro-per-roma-con-il-cadavere-del-figlio-in-borsa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6831-in-giro-per-roma-con-il-cadavere-del-figlio-in-borsa\/","title":{"rendered":"In giro per Roma con il cadavere del figlio in borsa"},"content":{"rendered":"<p><strong>ROMA<\/strong> &#8211; La &#8220;passeggiata&#8221; per le vie di Roma di una 25enne, residente nella Capitale, ha dell&#8217;incredibile, con tratti di macabro e tragico. La donna ha partorito privatamente<\/p>\n<p>  <!--more-->  <\/p>\n<p>il suo bambino, probabilmente nato senza vita. Cos\u00ec ha messo il suo piccolo corpicino nella borsa e, per circa 20 ore, lo ha tenuto nascosto senza preoccuparsene. Dopo il parto, e dopo aver occultato il piccolo cadavere, la donna ha incontrato un&#8217;amica per un aperitivo, raccontandole di aver abortito alcuni giorni prima. Dopo il pomeriggio passato tra chiacchere e risate, la donna \u00e8 salita in autobus e, a causa di un&#8217;emorragia, si \u00e8 recata presso l&#8217;ospedale San Camillo. Prima della visita ha gettato il piccolo nel cassonetto della spazzatura. Una storia assolutamente priva di ogni tipo di rispetto per la vita umana, la vita di un bambino nato dalla madre sbagliata. La donna \u00e8 stata arrestata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; La &#8220;passeggiata&#8221; per le vie di Roma di una 25enne, residente nella Capitale, ha dell&#8217;incredibile, con tratti di macabro e tragico. La donna ha partorito privatamente<\/p>\n","protected":false},"author":22,"featured_media":18682,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-18681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=18681"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/18682"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=18681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=18681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=18681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}