{"id":187106,"date":"2023-02-16T17:14:56","date_gmt":"2023-02-16T16:14:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=187106"},"modified":"2023-02-16T17:14:56","modified_gmt":"2023-02-16T16:14:56","slug":"guardia-medica-aggredita-da-infermiere-paziente-ennesimo-atto-di-violenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/guardia-medica-aggredita-da-infermiere-paziente-ennesimo-atto-di-violenza\/","title":{"rendered":"Guardia medica aggredita da infermiere-paziente: \u00abennesimo atto di violenza\u00bb"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; <strong>Un medico in servizio alla postazione di continuit\u00e0 assistenziale di Reggio Nord<\/strong>, in Viale Amendola, a Reggio Calabria, <strong>\u00e8 stato<\/strong> <strong>aggredito la notte scorsa da un giovane<\/strong> che \u00e8 risultato poi essere un infermiere. <strong>Lo denuncia l&#8217;Ordine dei medici di Reggio Calabria<\/strong> che, in una nota, esprime il proprio &#8220;sdegno per l&#8217;ennesimo episodio di violenza&#8221; nei confronti di un medico.<\/p>\n<p>Il dottore, ricostruisce l&#8217;Ordine nella nota, ha preso servizio verso le 20 di ieri sera con una collega e dopo mezzanotte un ragazzo ed una ragazza, &#8220;successivamente<strong> presentatisi come due infermieri,<\/strong> ed \u00e8 questa la cosa pi\u00f9 grave&#8221;, hanno citofonato chiedendo una prescrizione di insulina essendo il giovane paziente diabetico. La collega del dottore, pur non negando la prescrizione, prosegue la nota dell&#8217;Ordine, ha fatto notare la stranezza della richiesta, fatta in piena notte, di un farmaco salvavita che ogni paziente diabetico dovrebbe avere a portata di mano. <strong>Il giovane, per\u00f2, &#8220;ha cominciato ad usare toni offensivi e minacciosi<\/strong>. A questo punto \u00e8 intervenuto il dottore che ha cercato di smorzare i toni invitando il giovane a calmarsi. Ma, per tutta risposta, ha ricevuto dallo stesso uno schiaffo che gli ha fatto volare via gli occhiali&#8221;. Le forze dell&#8217;ordine, giunte in pochi minuti, hanno identificato i due infermieri ed hanno raccolto le dichiarazioni dei medici.<\/p>\n<p>Il presidente dell&#8217;Ordine dei medici di Reggio Pasquale Veneziano, &#8220;interpretando i sentimenti di solidariet\u00e0 di tutti gli iscritti &#8211; \u00e8 scritto nella nota &#8211; esprime solidariet\u00e0 e vicinanza al collega per l&#8217;aggressione sub\u00ecta, stigmatizzando l&#8217;ennesimo episodio di violenza. <strong>Episodi che si ripetono ormai con preoccupante frequenza<\/strong>, s<strong>oprattutto presso le postazioni di continuit\u00e0 assistenziale e i Pronto soccorso<\/strong> dove i medici operano, spesso in condizioni difficili, con grande spirito di abnegazione&#8221;. &#8220;Si tratta dell&#8217;ennesimo episodio di violenza &#8211; afferma Veneziano &#8211; che ripropone in tutta la sua drammaticit\u00e0 e urgenza l&#8217;esigenza di intervenire con provvedimenti organici e definitivi per garantire la sicurezza degli operatori e dei cittadini che afferiscono alle cure di questi presidi fondamentali del nostro sistema sanitario&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Un medico in servizio alla postazione di continuit\u00e0 assistenziale di Reggio Nord, in Viale Amendola, a Reggio Calabria, \u00e8 stato aggredito la notte scorsa da un giovane che \u00e8 risultato poi essere un infermiere. Lo denuncia l&#8217;Ordine dei medici di Reggio Calabria che, in una nota, esprime il proprio &#8220;sdegno per l&#8217;ennesimo [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":176331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-187106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/187106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=187106"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/187106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/176331"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=187106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=187106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=187106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}