{"id":187303,"date":"2023-02-16T19:27:27","date_gmt":"2023-02-16T18:27:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=187303"},"modified":"2023-02-16T19:27:27","modified_gmt":"2023-02-16T18:27:27","slug":"cassano-beccati-a-rubare-quintali-di-arance-da-terreno-comunale-denunciati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cassano-beccati-a-rubare-quintali-di-arance-da-terreno-comunale-denunciati\/","title":{"rendered":"Cassano, beccati a rubare quintali di arance da terreno comunale: denunciati"},"content":{"rendered":"<p>CASSANO ALLO IONIO (CS) &#8211; Stamattina, persone in corso di identificazione, sono state <strong>scoperte mentre asportavano quintali di arance con un camioncino da un terreno di propriet\u00e0 comunale.<\/strong> Lo stesso \u00e8 situato in localit\u00e0 Bruscata Piccola ed \u00e8 stato oggetto, da parte del Comune di Cassano, di un avviso ad evidenza pubblica per la manutenzione, la cura e la vendita dei prodotti agricoli che l&#8217;agrumeto \u00e8 in grado di produrre ma, al momento, non risulta ancora affidato e, pertanto, le arance sono rimaste non raccolte e nelle disponibilit\u00e0 dell&#8217;Ente. Qualcuno, quindi, stamane alla luce del sole con tanto di camioncino, secchi e cassette, ha pensato bene di intrufolarsi nel fondo e farne man bassa.<\/p>\n<p>Da quanto emerso, <strong>la frutta poi sarebbe state rivenduta illegalmente portando guadagni ai malfattori.<\/strong> Ma le cose sono andate diversamente: una pattuglia della Polizia Locale \u2013 guidata dalla comandante Anna Maria Aiello \u2013 nel corso di un quotidiano e continuo servizio di perlustrazione e controllo del territorio e dei beni comunali da lei disposto, ha notato l&#8217;anomalia ed \u00e8 subito intervenuta bloccando l&#8217;azione illegale. Se non fosse intervenuta in tempo, avrebbero asportato tutte le arance presenti nel fondo. Sul posto poi si sono recati anche, a supporto dei vigili, i Carabinieri della Compagnia di Cassano guidati dal Capitano Michele Ornelli.<\/p>\n<p>&#8220;Voglio subito sgombrare il campo da ogni dubbio \u2013 ha esordito<strong> il sindaco Gianni Papasso<\/strong> \u2013 sulla tutela del patrimonio pubblico io e la mia amministrazione non facciamo sconti a nessuno. Per questo motivo, terminata l&#8217;identificazione, accertato il preliminare svolgimento dei fatti, per tramite dell&#8217;ufficio Patrimonio<strong> abbiamo provveduto a sporgere denuncia contro i soggetti pescati<\/strong> a raccogliere agrumi illegalmente nel fondo di propriet\u00e0 del Comune. Ora l&#8217;autorit\u00e0 giudiziaria provveder\u00e0 a fare il suo corso e, al momento opportuno, ci costituiremo parte civile. Abbiamo un patrimonio pubblico da tutelare e non ci tiriamo indietro. Infine \u2013 ha concluso il sindaco Papasso \u2013 annuncio alla collettivit\u00e0 che ci sono stati riconsegnati tutti i quintali di arance asportate illegalmente e queste verranno r<strong>edistribuite alla collettivit\u00e0 conferendone parte al banco solidale alimentare<\/strong>\u00a0gestito da noi, parte a Casa Serena e parte a tutti gli istituti che provvederanno a loro volta a\u00a0consegnarle\u00a0a cittadini e bisognosi&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASSANO ALLO IONIO (CS) &#8211; Stamattina, persone in corso di identificazione, sono state scoperte mentre asportavano quintali di arance con un camioncino da un terreno di propriet\u00e0 comunale. Lo stesso \u00e8 situato in localit\u00e0 Bruscata Piccola ed \u00e8 stato oggetto, da parte del Comune di Cassano, di un avviso ad evidenza pubblica per la manutenzione, [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":187983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[],"class_list":["post-187303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/187303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=187303"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/187303\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/187983"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=187303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=187303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=187303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}