{"id":18869,"date":"2013-03-05T12:01:53","date_gmt":"2013-03-05T11:01:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=18869"},"modified":"2023-01-17T13:16:48","modified_gmt":"2023-01-17T12:16:48","slug":"6941-malore-durante-una-partita-di-calcetto-muore-22enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6941-malore-durante-una-partita-di-calcetto-muore-22enne\/","title":{"rendered":"Malore durante una partita di calcetto, muore 22enne"},"content":{"rendered":"<p><strong>PONTEDERA<\/strong> &#8211; Stava giocando a calcetto e, dopo un malore, \u00e8 morto. Un ragazzo di 22 anni di Pontedera \u00e8 deceduto la notte scorsa all&#8217;ospedale. Da quanto spiegato il ventiduenne ieri sera ha avuto un malore<\/p>\n<p>  <!--more-->  <\/p>\n<p>durante una partita di calcetto all&#8217;impianto sportivo Stella Azzurra e si e&#8217; accasciato in campo davanti ai compagni. Il primo a prestargli soccorso e&#8217; stato un infermiere che era tra il pubblico, poi sono intervenuti i sanitari del 118, infine il trasporto all&#8217;ospedale. Un epilogo tragico per un&#8217;et\u00e0 prematura.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PONTEDERA &#8211; Stava giocando a calcetto e, dopo un malore, \u00e8 morto. Un ragazzo di 22 anni di Pontedera \u00e8 deceduto la notte scorsa all&#8217;ospedale. Da quanto spiegato il ventiduenne ieri sera ha avuto un malore<\/p>\n","protected":false},"author":22,"featured_media":18870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-18869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=18869"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18869\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/18870"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=18869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=18869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=18869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}