{"id":18873,"date":"2013-03-05T12:16:42","date_gmt":"2013-03-05T11:16:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=18873"},"modified":"2023-01-17T13:16:48","modified_gmt":"2023-01-17T12:16:48","slug":"6943-tenta-di-uccidere-il-padre-della-fidanzata-un-arresto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6943-tenta-di-uccidere-il-padre-della-fidanzata-un-arresto\/","title":{"rendered":"Tenta di uccidere il padre della fidanzata, un arresto"},"content":{"rendered":"<p><p><span style=\"font-size: 12px; line-height: 1;\"><strong>NAPOLI<\/strong> &#8211; Il padre si opponeva alla relazione cos\u00ec un 30enne di Napoli, R.G., ha tentato di uccidere il padre della fidanzata con un colpo di pistola. L&#8217;uomo \u00e8 stato arrestato all&#8217; alba dalla Polizia a San Giorgio a Cremano <\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"font-size: 12px; line-height: 1;\">(Napoli). Ma la storia non finisce qui. L&#8217;uomo, 30 anni, aveva una relazione con una ragazza di 16 anni, oggi con l&#8217;obbligo di permanenza in casa e con l&#8217;accusa di spaccio di stupefacenti Denunciata, la polizia sta cercando di chiarire il suo ruolo.<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NAPOLI &#8211; Il padre si opponeva alla relazione cos\u00ec un 30enne di Napoli, R.G., ha tentato di uccidere il padre della fidanzata con un colpo di pistola. L&#8217;uomo \u00e8 stato arrestato all&#8217; alba dalla Polizia a San Giorgio a Cremano<\/p>\n","protected":false},"author":22,"featured_media":18874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-18873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=18873"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/18874"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=18873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=18873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=18873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}