{"id":18909,"date":"2013-03-05T15:34:39","date_gmt":"2013-03-05T14:34:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=18909"},"modified":"2023-01-17T13:16:50","modified_gmt":"2023-01-17T12:16:50","slug":"6961-studente-universitario-ucciso-a-catanzaro-fissato-appello","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6961-studente-universitario-ucciso-a-catanzaro-fissato-appello\/","title":{"rendered":"Studente universitario ucciso a Catanzaro, fissato appello"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CATANZARO<\/strong> &#8211; E&#8217; previsto per il 19 marzo l&#8217;inizio del&nbsp;processo d&#8217;appello per Cosimo Berlingieri e Gianluca Passalacqua,&nbsp;catanzaresi di etnia rom, di 44 e 23<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">anni, imputati per l&#8217;omicidio&nbsp;pluriaggravato del giovane universitario Massimiliano&nbsp;Citriniti, di 24 anni, accoltellato a morte il 22 febbraio 2009 fuori dal Centro<\/p>\n<p style=\"text-align: justify;\">commerciale &#8220;Le Fornaci&#8221;, a Catanzaro. I due uomini sono stati&nbsp;condannati, il 15 marzo scorso, a 21 anni e tre mesi di reclusione&nbsp;Berlingieri, ed a 10 anni di reclusione Passalacqua dalla Corte&nbsp;d&#8217;assise di Catanzaro che ha emesso la propria decisione dopo quasi&nbsp;dieci ore di camera di consiglio, e dopo aver riconosciuto per&nbsp;entrambi le attenuanti generiche prevalenti su alcune delle contestate&nbsp;aggravanti, mente altre sono cadute (il pubblico ministero, Simona<\/p>\n<p style=\"text-align: justify;\">Rossi, aveva chiesto per gli imputati la condanna all&#8217;ergastolo).<\/p>\n<p style=\"text-align: justify;\">I giudici di primo grado hanno inoltre&nbsp;riconosciuto alle parti civili, rappresentate dall&#8217;avvocato Francesco&nbsp;Gambardella, il risarcimento del danno da liquidarsi in altra sede,&nbsp;attribuendo intanto provvisionali da 100.000 euro ciascuno alla madre&nbsp;ed al padre della vittima, e da 50.000 euro al fratello di&nbsp;Massimiliano. I difensori di Berlingieri e Passalacqua, gli avvocati&nbsp;Salvatore Staiano, Gregorio Viscomi, e Nicola Tavano, avevano fin da&nbsp;subito annunciato di voler proporre appello. Secondo quanto sostenuto&nbsp;dalla pubblica accusa, Citriniti sarebbe stato ammazzato a seguito di&nbsp;un banale scherzo fatto con della schiuma spruzzata in faccia ad un&nbsp;minorenne rom, che avrebbe dato vita ad una lite iniziata dentro al&nbsp;centro commerciale, e ripresa all&#8217;esterno piu&#8217; tardi, dove il 24enne&nbsp;e&#8217; stato ucciso, sempre secondo le accuse, dopo essere stato bloccato&nbsp;da diverse persone che lo hanno aggredito.<\/p>\n<p style=\"text-align: justify;\">Tra queste persone, secondo&nbsp;la Procura, ci sarebbero stati Berlingieri e Passalacqua. A poche ore&nbsp;dal delitto le indagini condussero i poliziotti della Squadra mobile&nbsp;proprio a casa di Cosimo Berlingieri, dove la moglie di quest&#8217;ultimo&nbsp;affido&#8217; loro il figlio minorenne, ammettendo subito che era stato&nbsp;coinvolto nello scontro avvenuto alle &#8220;Fornaci&#8221;. Il ragazzo&nbsp;diciassettenne, che e&#8217; anche cognato di Passalacqua, e&#8217; gia&#8217; stato&nbsp;giudicato con rito abbreviato e condannato in primo grado a 14 anni e&nbsp;15 giorni di galera, poi scontati a 10 anni dalla Corte d&#8217;appello con&nbsp;una sentenza infine confermata dalla Cassazione il 19 ottobre 2011.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; E&#8217; previsto per il 19 marzo l&#8217;inizio del&nbsp;processo d&#8217;appello per Cosimo Berlingieri e Gianluca Passalacqua,&nbsp;catanzaresi di etnia rom, di 44 e 23<\/p>\n","protected":false},"author":22,"featured_media":18910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-18909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=18909"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/18910"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=18909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=18909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=18909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}